{"id":32252,"date":"2024-01-29T20:06:39","date_gmt":"2024-01-29T20:06:39","guid":{"rendered":"https:\/\/youngexplorersclub.ch\/unverzichtbarer-leitfaden-was-sie-fuer-eine-perfekte-reise-in-die-schweiz-einpacken-sollten\/"},"modified":"2026-06-20T18:03:22","modified_gmt":"2026-06-20T18:03:22","slug":"unverzichtbarer-leitfaden-was-sie-fuer-eine-perfekte-reise-in-die-schweiz-einpacken-sollten","status":"publish","type":"post","link":"https:\/\/youngexplorersclub.ch\/de\/unverzichtbarer-leitfaden-was-sie-fuer-eine-perfekte-reise-in-die-schweiz-einpacken-sollten\/","title":{"rendered":"Unverzichtbarer Leitfaden: Was Sie f\u00fcr eine perfekte Reise in die Schweiz einpacken sollten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wenn Sie eine Reise in die Schweiz antreten, stellt sich oft die Frage: Was muss ich f\u00fcr die Schweiz einpacken? In unserem Leitfaden finden Sie eine Liste mit den wichtigsten Dingen, die Sie f\u00fcr die Schweizer Alpen, die gesch\u00e4ftigen St\u00e4dte und die ruhigen Seeufer einpacken sollten. Finden Sie heraus, was Sie mitnehmen sollten, um Ihr Erlebnis zu optimieren, ohne sich zu \u00fcbernehmen.  <\/p>\n\n<h2 class=\"wp-block-heading\">Wichtigste Erkenntnisse<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><p>Packen Sie vielseitige Kleidungsschichten und bequeme Wanderschuhe sowie saisonale Ausr\u00fcstung wie warme Kleidung f\u00fcr den Wintersport ein.<\/p><\/li><li><p>Nehmen Sie wichtige Dokumente, Gesundheits- und Sicherheitsartikel sowie technische Ger\u00e4te wie einen Stromadapter und eine Kamera mit, um Ihre Reise zu dokumentieren.<\/p><\/li><li><p>Statten Sie sich mit funktionellen und stilvollen Accessoires aus: Schutzausr\u00fcstung f\u00fcr den Au\u00dfenbereich, Multitools f\u00fcr Erkundungen und stilvolle Extras f\u00fcr genussvolle Momente.<\/p><\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Swiss Packing Essentials f\u00fcr alle Jahreszeiten<\/h2>\n\n<figure class=\"wp-block-image\">\n<img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2024\/01\/image-placeholder.png\" alt=\"Ein Rucksack gef&#xFC;llt mit verschiedenen Reiseutensilien f&#xFC;r eine Reise in die Schweiz\" title=\"\">\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Lassen Sie uns zun\u00e4chst die wichtigsten Dinge f\u00fcr die Schweiz besprechen, bevor wir auf die Einzelheiten eingehen. Unabh\u00e4ngig von der Jahreszeit sollten Sie bequeme Wanderschuhe und Kleidung einpacken, die Sie in mehreren Schichten tragen k\u00f6nnen, darunter leichte Pullover f\u00fcr k\u00fchlere Abende und warme Kleidung f\u00fcr die Winterwanderungen. Vergessen Sie nicht Ihre Packliste f\u00fcr den Winter, wenn Sie einen Besuch in den k\u00e4lteren Monaten planen &#8211; denken Sie an warme Pullover, Schneestiefel und eine Skijacke f\u00fcr den Wintersport!  <\/p>\n\n<p class=\"wp-block-paragraph\">Als n\u00e4chstes werden wir die wesentlichen Punkte im Detail untersuchen.<\/p>\n\n<h3 class=\"wp-block-heading\">Wichtige Dokumente und Geldverwaltung<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn es um Dokumente geht, ist Ihr Reisepass das Wichtigste &#8211; stellen Sie sicher, dass er noch mindestens sechs Monate g\u00fcltig ist. F\u00fcr allt\u00e4gliche Ausgaben werden Kreditkarten weitgehend akzeptiert, aber es ist immer eine gute Idee, ein paar Schweizer Franken f\u00fcr gelegentliche Situationen, in denen Sie nur Bargeld ben\u00f6tigen, zur Hand zu haben. <\/p>\n\n<p class=\"wp-block-paragraph\">Denken Sie daran, dass lange Hosen, einschlie\u00dflich Skihosen, und lang\u00e4rmelige Hemden f\u00fcr k\u00fchlere Abende im Schweizer Sommer immer noch notwendig sind.<\/p>\n\n<h3 class=\"wp-block-heading\">Ausr\u00fcstung f\u00fcr Gesundheit und Sicherheit<\/h3>\n\n<p class=\"wp-block-paragraph\">Ihre Gesundheit und Sicherheit stehen an erster Stelle. Packen Sie immer Ihre verschriebenen Medikamente und einen Erste-Hilfe-Kasten ein, besonders wenn Sie Winterwanderungen planen. Vergessen Sie nicht, Ihre Impfungen aufzufrischen, u.a. COVID-19 und Hepatitis A und B.  <\/p>\n\n<p class=\"wp-block-paragraph\">Eine gute Vorbereitung kann den Unterschied zwischen einem unvergesslichen Urlaub und einem unangenehmen Erlebnis ausmachen.<\/p>\n\n<h3 class=\"wp-block-heading\">Technik und Gadgets<\/h3>\n\n<p class=\"wp-block-paragraph\">Im heutigen digitalen Zeitalter ist es wichtig, immer in Verbindung zu bleiben. Hier sind einige wichtige Dinge, die Sie mitnehmen sollten: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><p>Typ-J-Netzadapter, damit Ihre Ger\u00e4te aufgeladen bleiben<\/p><\/li><li><p>Holafly eSIM f\u00fcr die Schweiz oder ein 4G Switzerland Pocket WiFi f\u00fcr nahtlose Konnektivit\u00e4t<\/p><\/li><li><p>Kamera, um die atemberaubenden Landschaften der Schweiz einzufangen<\/p><\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Schweiz Saisonale Garderobe Guide<\/h2>\n\n<figure class=\"wp-block-image\">\n<img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2024\/01\/92944181-fad0-4dd4-bc7a-71de024e2b27.png\" alt=\"Eine Kollektion von Winterkleidung wie Skijacken, Schneestiefel und warme Pullover\" title=\"\">\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Nachdem wir die Grundlagen behandelt haben, gehen wir nun dazu \u00fcber, uns f\u00fcr die Schweizer Jahreszeiten angemessen zu kleiden. Das Wichtigste ist, dass Sie Kleidung einpacken, die f\u00fcr schwankende Temperaturen und Wetterbedingungen geeignet ist. <\/p>\n\n<p class=\"wp-block-paragraph\">Ob Sie die Schweizer Skigebiete im Winter besuchen oder den Schweizer Sommer genie\u00dfen, wir haben alles f\u00fcr Sie.<\/p>\n\n<h3 class=\"wp-block-heading\">Fr\u00fchlingspracht: Kleidung f\u00fcr M\u00e4rz bis Mai<\/h3>\n\n<p class=\"wp-block-paragraph\">Der Fr\u00fchling in der Schweiz zeichnet sich durch milde Temperaturen aus. Packen Sie: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><p>Leichte Pullover<\/p><\/li><li><p>Jeans<\/p><\/li><li><p>Eine Jacke f\u00fcr k\u00fchlere Tage, besonders wenn Sie St\u00e4dte im Flachland wie Z\u00fcrich, Genf und Lugano besuchen, wo die Temperaturen im April bei angenehmen 17\u00b0C liegen.<\/p><\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Sommerliche Gen\u00fcsse: Outfits f\u00fcr Juni bis August<\/h3>\n\n<p class=\"wp-block-paragraph\">Der Sommer ist perfekt, um die Schweizer Kultur zu genie\u00dfen. Leichte, atmungsaktive Kleidung wie Hemden aus Baumwolle oder Leinen, kurze Hosen oder Sommerkleider sind ideal. Vergessen Sie nicht eine leichte Jacke oder einen Pullover f\u00fcr k\u00fchlere Abende.  <\/p>\n\n<h3 class=\"wp-block-heading\">Herbst-Abenteuer: September bis November Ensembles<\/h3>\n\n<p class=\"wp-block-paragraph\">Der Herbst in der Schweiz verlangt nach verschiedenen Schichten. Packen Sie gem\u00fctliche Pullover, Jeans und Stiefel ein. F\u00fcgen Sie eine mittelschwere Jacke und einen Schal f\u00fcr zus\u00e4tzliche W\u00e4rme hinzu. Das Ziel ist es, gleichzeitig warm und modisch zu sein.   <\/p>\n\n<h3 class=\"wp-block-heading\">Winter Wonderland: Dezember bis Februar Kleidung<\/h3>\n\n<p class=\"wp-block-paragraph\">Der Winter in der Schweiz ist ein Winterwunderland, aber die Temperaturen k\u00f6nnen deutlich sinken. Packen Sie warme Kleidung wie: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><p>dicke Pullover<\/p><\/li><li><p>Thermo-Basisschichten<\/p><\/li><li><p>Jeans<\/p><\/li><li><p>eine warme Jacke<\/p><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Vergessen Sie Ihre Winterstiefel nicht, um Ihre F\u00fc\u00dfe beim Wintersport warm zu halten.<\/p>\n\n<h2 class=\"wp-block-heading\">Schuhe f\u00fcr jede Schweizer Reise<\/h2>\n\n<figure class=\"wp-block-image\">\n<img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2024\/01\/86768357-856c-4818-b566-2041341cc849.png\" alt=\"Eine Vielzahl von Schuhen, darunter Wanderschuhe, Walkingschuhe und Skistiefel\" title=\"\">\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Die Wahl des Schuhwerks in der Schweiz kann Ihren Tag entscheidend beeinflussen. Ob Sie nun in den Alpen wandern, die Stra\u00dfen der Stadt erkunden oder einen Tag am See genie\u00dfen, wir haben den perfekten Schuhf\u00fchrer f\u00fcr Sie. <\/p>\n\n<h3 class=\"wp-block-heading\">Wanderschuhe f\u00fcr Bergpfade<\/h3>\n\n<p class=\"wp-block-paragraph\">Beim Wandern in den Alpen ist der Komfort der F\u00fc\u00dfe entscheidend. Ziehen Sie einen guten Sportschuh oder einen leichten, niedrig geschnittenen Trailrunner in Betracht. Vergessen Sie nicht, sich bei beliebten Marken wie Salomon, On und Hanwag nach ihrer Auswahl an Outdoor-Schuhen umzusehen.  <\/p>\n\n<h3 class=\"wp-block-heading\">Stilvolle und dennoch bequeme Wanderschuhe<\/h3>\n\n<p class=\"wp-block-paragraph\">Bei einem Spaziergang durch die Stadt sind sowohl Stil als auch Komfort gefragt. Entscheiden Sie sich f\u00fcr einen hochwertigen, wasserdichten Oxford-Schuh aus Leder oder einen Stiefel mit einer Vibram-Stollensohle. <\/p>\n\n<p class=\"wp-block-paragraph\">Ihr Komfort ist entscheidend, w\u00e4hrend Sie in die Schweizer Kultur eintauchen!<\/p>\n\n<h3 class=\"wp-block-heading\">Spezialisiertes Schuhwerk f\u00fcr Winter- und Wasseraktivit\u00e4ten<\/h3>\n\n<p class=\"wp-block-paragraph\">F\u00fcr Wintersport und Aktivit\u00e4ten im Wasser sollten Sie sich f\u00fcr spezielles Schuhwerk entscheiden. Warme, wasserdichte Stiefel mit festem Halt sind f\u00fcr Winterabenteuer unverzichtbar, w\u00e4hrend ein gutes Paar wasserdichte Lederschuhe oder bequeme Sandalen perfekt f\u00fcr Wasseraktivit\u00e4ten sind. <\/p>\n\n<h2 class=\"wp-block-heading\">Zubeh\u00f6r f\u00fcr ein besseres Schweizer Erlebnis<\/h2>\n\n<figure class=\"wp-block-image\">\n<img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2024\/01\/fc193151-a7bd-4d87-9247-648be7f5b4af.png\" alt=\"Wandern, Entspannung, Natur\" title=\"\">\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Accessoires k\u00f6nnen Ihrem Schweizer Reiseerlebnis das gewisse Etwas verleihen. Ob Schutzausr\u00fcstung f\u00fcr Outdoor-Abenteuer, funktionelle Accessoires f\u00fcr den Alltag oder luxuri\u00f6se Gegenst\u00e4nde f\u00fcr die Freizeit, wir haben alles f\u00fcr Sie! <\/p>\n\n<h3 class=\"wp-block-heading\">Schutzausr\u00fcstung f\u00fcr Outdoor-Abenteuer<\/h3>\n\n<p class=\"wp-block-paragraph\">Bei Abenteuern im Freien ist Schutzausr\u00fcstung ein Muss, einschlie\u00dflich Sonnenschutz. Vergessen Sie nicht, Ihre Sonnenbrille, M\u00fctzen, Handschuhe und eine Regenjacke einzupacken. <\/p>\n\n<p class=\"wp-block-paragraph\">Geben Sie der Sicherheit immer den Vorrang!<\/p>\n\n<h3 class=\"wp-block-heading\">Funktionale Add-ons f\u00fcr die t\u00e4gliche Erkundung<\/h3>\n\n<p class=\"wp-block-paragraph\">Funktionale Zusatzger\u00e4te k\u00f6nnen Ihre t\u00e4glichen Erkundungen angenehmer machen. Nehmen Sie beispielsweise ein 15-in-1-Multitool-Messer und einen Fitness-Tracker mit, um Ihre Aktivit\u00e4ten zu verfolgen. <\/p>\n\n<h3 class=\"wp-block-heading\">Extras f\u00fcr Freizeit und Luxus<\/h3>\n\n<p class=\"wp-block-paragraph\">Warum nicht einen Hauch von Luxus in Ihr Schweizer Erlebnis einbauen? Packen Sie doch einen Pashmina-Schal oder ein Tuch und eine schicke Uhr ein. Sie sind ja schlie\u00dflich im Urlaub!  <\/p>\n\n<h2 class=\"wp-block-heading\">Besondere \u00dcberlegungen f\u00fcr einzigartige Schweizer Erlebnisse<\/h2>\n\n<p class=\"wp-block-paragraph\">Die Schweiz bietet eine F\u00fclle von einzigartigen Erlebnissen. Vom Skifahren in den Alpen \u00fcber die Entspannung an den Seen bis hin zur Erkundung des kulturellen Erbes &#8211; mit dem richtigen Gep\u00e4ck lassen sich diese Erlebnisse noch steigern. <\/p>\n\n<h3 class=\"wp-block-heading\">Packen f\u00fcr die Gipfel: Skigebiete und Alpenausfl\u00fcge<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn Sie sich auf den Weg zu den Schweizer Gipfeln machen, sollten Sie Ihre Skiausr\u00fcstung nicht vergessen. Packen Sie Ihre Skier, Schuhe, St\u00f6cke und eine gute Skijacke ein. <\/p>\n\n<p class=\"wp-block-paragraph\">Achten Sie beim Bergsteigen darauf, dass Sie Ihren Klettergurt mit Materialschlaufen, Klettereispickel und anderer notwendiger Ausr\u00fcstung einpacken.<\/p>\n\n<h3 class=\"wp-block-heading\">Genie\u00dfen Sie die Schweizer Wasserlandschaft: Seen und Thermalb\u00e4der<\/h3>\n\n<p class=\"wp-block-paragraph\">Ein Tag an einem Schweizer See oder einer Thermalquelle kann sehr entspannend sein. Denken Sie daran, eine wiederverwendbare Wasserflasche und eine Picknickdecke f\u00fcr einen perfekten Tag am Wasser einzupacken. <\/p>\n\n<h3 class=\"wp-block-heading\">Stadtbesichtigungen und kulturelle Begegnungen<\/h3>\n\n<p class=\"wp-block-paragraph\">Beim Sightseeing in der Stadt ist Komfort das A und O. Packen Sie bequeme Schuhe und einen Tagesrucksack ein und vergessen Sie nicht Ihre Kamera, um die kulturellen Wunder von St\u00e4dten wie Z\u00fcrich, Basel und Genf festzuhalten. <\/p>\n\n<h2 class=\"wp-block-heading\">Praktische Tipps f\u00fcr cleveres Packen<\/h2>\n\n<figure class=\"wp-block-image\">\n<img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2024\/01\/d1197b16-c205-4c1e-932c-34fffab63db6.png\" alt=\"Effizient gepacktes Gep&#xE4;ck mit ordentlich organisierter Kleidung und wichtigen Dingen\" title=\"\">\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Intelligentes Packen kann Ihnen in Ihrem Schweizer Urlaub viel \u00c4rger ersparen. Wir haben einige praktische Tipps f\u00fcr Sie, die von Komprimierungs- und Organisationstechniken bis hin zur Auswahl des geeigneten Gep\u00e4cks reichen. <\/p>\n\n<h3 class=\"wp-block-heading\">Komprimierung und Organisationstechniken<\/h3>\n\n<p class=\"wp-block-paragraph\">Komprimierungstechniken wie die Verwendung von Vakuumbeuteln k\u00f6nnen Ihnen helfen, mehr in Ihrem Gep\u00e4ck unterzubringen.<\/p>\n\n<p class=\"wp-block-paragraph\">Mit Packw\u00fcrfeln k\u00f6nnen Sie Ihre Habseligkeiten geordnet und leicht auffindbar halten.<\/p>\n\n<h3 class=\"wp-block-heading\">Die Auswahl des richtigen Gep\u00e4cks<\/h3>\n\n<p class=\"wp-block-paragraph\">Die Auswahl des richtigen Gep\u00e4cks kann Ihre Reise angenehmer machen. Ber\u00fccksichtigen Sie die Art der Aktivit\u00e4ten, die Sie unternehmen werden, und w\u00e4hlen Sie einen Gep\u00e4cktyp, der Ihren Bed\u00fcrfnissen entspricht, sei es ein Rucksack zum Wandern oder ein Koffer f\u00fcr die Erkundung der Stadt. <\/p>\n\n<h3 class=\"wp-block-heading\">Last-Minute-Checkliste<\/h3>\n\n<p class=\"wp-block-paragraph\">Eine Last-Minute-Checkliste kann sicherstellen, dass Sie alles eingepackt haben, was Sie f\u00fcr Ihr Schweizer Abenteuer brauchen. Von Winterm\u00e4nteln und warmen Stiefeln bis hin zum Erste-Hilfe-Kasten &#8211; stellen Sie sicher, dass Sie alles dabei haben, bevor Sie zum Flughafen fahren! <\/p>\n\n<h2 class=\"wp-block-heading\">Zusammenfassung<\/h2>\n\n<p class=\"wp-block-paragraph\">Ganz gleich, ob Sie in die Schweiz reisen, um einen entspannten Urlaub am See zu verbringen, ein aufregendes Skiabenteuer zu erleben oder eine kulturelle Stadt zu erkunden &#8211; mit dem richtigen Gep\u00e4ck k\u00f6nnen Sie Ihr Erlebnis verbessern. Mit diesem Leitfaden k\u00f6nnen Sie eine komfortable und angenehme Reise in das Schweizer Wunderland sicherstellen! <\/p>\n\n<h2 class=\"wp-block-heading\">H\u00e4ufig gestellte Fragen<\/h2>\n\n<h3 class=\"wp-block-heading\">Wie sollte ich mich f\u00fcr eine Reise in die Schweiz kleiden?<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn Sie die Schweiz besuchen, ziehen Sie leichte, atmungsaktive Kleidung f\u00fcr Aktivit\u00e4ten am Tag an und packen Sie einen leichten Pullover oder eine Jacke f\u00fcr k\u00fchlere Abende oder hochgelegene Gebiete ein. Nehmen Sie au\u00dferdem bequeme Wanderschuhe mit, um die Gegend zu erkunden. Packen Sie entsprechend f\u00fcr Ihre Reise!  <\/p>\n\n<h3 class=\"wp-block-heading\">Kann ich in der Schweiz Turnschuhe tragen?<\/h3>\n\n<p class=\"wp-block-paragraph\">Ja, Sie k\u00f6nnen in der Schweiz Turnschuhe tragen, da der Kleidungsstil sowohl konservativ als auch leger ist.<\/p>\n\n<h3 class=\"wp-block-heading\">Welche Lebensmittel sollte ich f\u00fcr die Schweiz einpacken?<\/h3>\n\n<p class=\"wp-block-paragraph\">Packen Sie Nudeln, Pasta, Fertiggerichte und Snacks f\u00fcr die Schweiz ein. Denken Sie daran, sich vegetarisch zu ern\u00e4hren, um Fleischkosten zu sparen, und nehmen Sie eine Lunchbox oder Ziplock-T\u00fcten f\u00fcr Lunchpakete mit. Gute Reise!  <\/p>\n\n<h3 class=\"wp-block-heading\">Was brauchen Sie, um in die Schweiz zu reisen?<\/h3>\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Einreise in die Schweiz ben\u00f6tigen Sie einen Reisepass, der mindestens 6 Monate \u00fcber das Abreisedatum hinaus g\u00fcltig ist und mindestens eine leere Seite aufweist. In einigen F\u00e4llen kann die Schweiz ein abgelaufenes Reisedokument akzeptieren. <\/p>\n\n<h3 class=\"wp-block-heading\">Wie packen Sie im Sommer f\u00fcr die Alpen?<\/h3>\n\n<p class=\"wp-block-paragraph\">Packen Sie eine Mischung aus sommerlicher und k\u00fchler Kleidung ein, darunter Tanktops, leichte Pullover, eine Jacke, kurze Hosen, Sandalen und Wanderschuhe f\u00fcr Ihre Sommerreise in die Alpen. Vergessen Sie Sonnencreme und Sonnenbrille nicht! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie eine Reise in die Schweiz antreten, stellt sich oft die Frage: Was muss ich f\u00fcr die Schweiz einpacken? In unserem Leitfaden finden Sie eine Liste mit den wichtigsten Dingen, die Sie f\u00fcr die Schweizer Alpen, die gesch\u00e4ftigen St\u00e4dte und die ruhigen Seeufer einpacken sollten. Finden Sie heraus, was Sie mitnehmen sollten, um Ihr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[],"footnotes":""},"categories":[],"tags":[],"class_list":["post-32252","post","type-post","status-publish","format-standard","hentry"],"wpml_language":null,"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"grivas","author_link":"https:\/\/youngexplorersclub.ch\/de\/author\/grivas\/"},"comment_info":"","category_info":[],"tag_info":false,"_links":{"self":[{"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/posts\/32252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/comments?post=32252"}],"version-history":[{"count":1,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/posts\/32252\/revisions"}],"predecessor-version":[{"id":72758,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/posts\/32252\/revisions\/72758"}],"wp:attachment":[{"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/media?parent=32252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/categories?post=32252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/de\/wp-json\/wp\/v2\/tags?post=32252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}