{"id":18322,"date":"2023-01-31T10:50:42","date_gmt":"2023-01-31T10:50:42","guid":{"rendered":"https:\/\/youngexplorersclub.ch\/campamento-de-verano-tour-du-mont-blanc\/"},"modified":"2026-06-09T17:19:10","modified_gmt":"2026-06-09T17:19:10","slug":"campamento-de-verano-tour-du-mont-blanc","status":"publish","type":"page","link":"https:\/\/youngexplorersclub.ch\/es\/campamento-de-verano-tour-du-mont-blanc\/","title":{"rendered":"Campamento de verano de senderismo: Tour du Mont Blanc para adolescentes"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id16174_88e217-7c{margin-top:-10px;}.kb-row-layout-id16174_88e217-7c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id16174_88e217-7c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id16174_88e217-7c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_88e217-7c > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id16174_88e217-7c ,.kb-row-layout-id16174_88e217-7c h1,.kb-row-layout-id16174_88e217-7c h2,.kb-row-layout-id16174_88e217-7c h3,.kb-row-layout-id16174_88e217-7c h4,.kb-row-layout-id16174_88e217-7c h5,.kb-row-layout-id16174_88e217-7c h6{color:var(--global-palette3, #1A202C);}.kb-row-layout-id16174_88e217-7c a{color:var(--global-palette5, #4A5568);}.kb-row-layout-id16174_88e217-7c a:hover{color:var(--global-palette6, #718096);}@media all and (max-width: 1024px){.kb-row-layout-id16174_88e217-7c > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-4xl, 8rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id16174_88e217-7c{margin-top:30px;}.kb-row-layout-id16174_88e217-7c > .kt-row-column-wrap{padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_88e217-7c alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{padding-top:0px;}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{border-top:0px solid var(--global-palette3, #1A202C);border-right:0px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette3, #1A202C);}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col,.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_5b7ae5-31{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{border-top:0px solid var(--global-palette3, #1A202C);border-right:0px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_5b7ae5-31 > .kt-inside-inner-col{border-top:0px solid var(--global-palette3, #1A202C);border-right:0px solid var(--global-palette3, #1A202C);border-left:0px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_5b7ae5-31 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kadence-column16174_e08312-3c > .kt-inside-inner-col,.kadence-column16174_e08312-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_e08312-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_e08312-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_e08312-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_e08312-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_e08312-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_e08312-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_e08312-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_e08312-3c kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25, .wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25[data-kb-block=\"kb-adv-heading16174_5da944-25\"]{max-width:1300px;margin-right:auto;margin-left:auto;text-align:center;font-size:120px;line-height:100px;font-weight:700;font-style:normal;font-family:'Roboto Condensed';text-transform:uppercase;letter-spacing:0.5px;color:#f0ece8;}.wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25[data-kb-block=\"kb-adv-heading16174_5da944-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_5da944-25[data-kb-block=\"kb-adv-heading16174_5da944-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading16174_5da944-25 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_5da944-25\">CAMPAMENTO DE VIAJES<\/h1>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id16174_bf3c9a-e5{margin-top:-40px;}.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );padding-bottom:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id16174_bf3c9a-e5{margin-top:0px;}.kb-row-layout-id16174_bf3c9a-e5 > .kt-row-column-wrap{column-gap:5px;row-gap:var(--global-kb-gap-none, 0rem );padding-bottom:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_bf3c9a-e5 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column16174_c13ce4-ea > .kt-inside-inner-col{padding-top:5px;}.kadence-column16174_c13ce4-ea > .kt-inside-inner-col,.kadence-column16174_c13ce4-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_c13ce4-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_c13ce4-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_c13ce4-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_c13ce4-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_c13ce4-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_c13ce4-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_c13ce4-ea > .kt-inside-inner-col{display:flex;flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_c13ce4-ea\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b, .wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b[data-kb-block=\"kb-adv-heading16174_dd4607-0b\"]{text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b[data-kb-block=\"kb-adv-heading16174_dd4607-0b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b[data-kb-block=\"kb-adv-heading16174_dd4607-0b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b, .wp-block-kadence-advancedheading.kt-adv-heading16174_dd4607-0b[data-kb-block=\"kb-adv-heading16174_dd4607-0b\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading16174_dd4607-0b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_dd4607-0b\">la visita al CAMPAMENTO del Mont Blanc<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_ff3af2-1b > .kt-inside-inner-col,.kadence-column16174_ff3af2-1b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_ff3af2-1b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_ff3af2-1b > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_ff3af2-1b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_ff3af2-1b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_ff3af2-1b{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_ff3af2-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_ff3af2-1b > .kt-inside-inner-col{display:flex;flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_ff3af2-1b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b, .wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b[data-kb-block=\"kb-adv-heading16174_eea231-2b\"]{text-align:center;font-weight:400;font-style:normal;font-family:Roboto;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b[data-kb-block=\"kb-adv-heading16174_eea231-2b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_eea231-2b[data-kb-block=\"kb-adv-heading16174_eea231-2b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading16174_eea231-2b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_eea231-2b\"><sub>un campamento de verano de mochileros para adolescentes<\/sub><\/h3>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-16174_dd2bdb-41 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_dd2bdb-41 .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_dd2bdb-41 .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_dd2bdb-41\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_893e03-f8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap{padding-top:20px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id16174_893e03-f8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_893e03-f8 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col,.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_92c2d1-f8{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_92c2d1-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_92c2d1-f8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34, .wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34[data-kb-block=\"kb-adv-heading16174_369c16-34\"]{text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34[data-kb-block=\"kb-adv-heading16174_369c16-34\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34[data-kb-block=\"kb-adv-heading16174_369c16-34\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34, .wp-block-kadence-advancedheading.kt-adv-heading16174_369c16-34[data-kb-block=\"kb-adv-heading16174_369c16-34\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading16174_369c16-34 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_369c16-34\">Puntos clave del programa:<\/h2>\n\n\n<style>.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col,.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_6e9d9b-46{text-align:center;}.kadence-column16174_6e9d9b-46{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_6e9d9b-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_6e9d9b-46\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-16174_cfd18c-bb .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_cfd18c-bb .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_cfd18c-bb .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_cfd18c-bb\"><div class=\"kt-block-spacer kt-block-spacer-halign-center kt-block-spacer-malign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_4c4b08-4e > .kt-inside-inner-col,.kadence-column16174_4c4b08-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_4c4b08-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_4c4b08-4e > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_4c4b08-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_4c4b08-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_4c4b08-4e{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_4c4b08-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_4c4b08-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_4c4b08-4e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box16174_6020c7-97 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box16174_6020c7-97 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-top:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box16174_6020c7-97 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box16174_6020c7-97 .kt-info-svg-icon-flip, .kt-info-box16174_6020c7-97 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box16174_6020c7-97 .kt-blocks-info-box-media{border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:0px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box16174_6020c7-97 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box16174_6020c7-97 .kt-infobox-textcontent h3.kt-blocks-info-box-title{letter-spacing:-0.7px;font-family:Nunito;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box16174_6020c7-97 .kt-blocks-info-box-text{font-size:16px;line-height:21px;font-family:Nunito;font-style:normal;font-weight:400;padding-top:8px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box16174_6020c7-97 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 767px){.kt-info-box16174_6020c7-97 .kt-blocks-info-box-link-wrap{text-align:left;}.kt-info-box16174_6020c7-97 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:15px;}.wp-block-kadence-infobox.kt-info-box16174_6020c7-97 .kt-blocks-info-box-text{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box16174_6020c7-97\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_tree kt-info-svg-icon\"><svg viewBox=\"0 0 384 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M377.33 375.429L293.906 288H328c21.017 0 31.872-25.207 17.448-40.479L262.79 160H296c20.878 0 31.851-24.969 17.587-40.331l-104-112.003c-9.485-10.214-25.676-10.229-35.174 0l-104 112.003C56.206 134.969 67.037 160 88 160h33.21l-82.659 87.521C24.121 262.801 34.993 288 56 288h34.094L6.665 375.429C-7.869 390.655 2.925 416 24.025 416H144c0 32.781-11.188 49.26-33.995 67.506C98.225 492.93 104.914 512 120 512h144c15.086 0 21.776-19.069 9.995-28.494-19.768-15.814-33.992-31.665-33.995-67.496V416h119.97c21.05 0 31.929-25.309 17.36-40.571z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong>Fechas y edades:<\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">M\u00faltiples sesiones este verano. Edades: 13 &#8211; 17.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-top:0px;}.kt-info-box16174_9a9fb3-e6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box16174_9a9fb3-e6 .kt-info-svg-icon-flip, .kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-media{border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:0px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box16174_9a9fb3-e6 .kt-infobox-textcontent h3.kt-blocks-info-box-title{letter-spacing:-0.7px;font-family:Nunito;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-text{font-size:16px;line-height:21px;font-family:Nunito;font-style:normal;font-weight:400;padding-top:8px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 767px){.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-link-wrap{text-align:left;}.kt-info-box16174_9a9fb3-e6 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:15px;}.wp-block-kadence-infobox.kt-info-box16174_9a9fb3-e6 .kt-blocks-info-box-text{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box16174_9a9fb3-e6\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><a href=\"https:\/\/maps.app.goo.gl\/VXMHV5rBV3KskXVt9\" target=\"_blank\" rel=\"noopener\">Ubicaci\u00f3n del campamento:<\/a><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Se trata de un campamento de viaje, en el que dormimos en varios lugares de la regi\u00f3n alpina del Mont Blanc.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box16174_b41fef-91 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box16174_b41fef-91 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-top:0px;}.kt-info-box16174_b41fef-91 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box16174_b41fef-91 .kt-info-svg-icon-flip, .kt-info-box16174_b41fef-91 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box16174_b41fef-91 .kt-blocks-info-box-media{border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:0px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box16174_b41fef-91 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box16174_b41fef-91 .kt-infobox-textcontent h3.kt-blocks-info-box-title{letter-spacing:-0.7px;font-family:Nunito;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box16174_b41fef-91 .kt-blocks-info-box-text{font-size:16px;line-height:21px;font-family:Nunito;font-style:normal;font-weight:400;padding-top:8px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box16174_b41fef-91 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 767px){.kt-info-box16174_b41fef-91 .kt-blocks-info-box-link-wrap{text-align:left;}.kt-info-box16174_b41fef-91 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:15px;}.wp-block-kadence-infobox.kt-info-box16174_b41fef-91 .kt-blocks-info-box-text{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box16174_b41fef-91\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_dollarSign kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"12\" y1=\"1\" x2=\"12\" y2=\"23\"\/><path d=\"M17 5H9.5a3.5 3.5 0 0 0 0 7h5a3.5 3.5 0 0 1 0 7H6\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong>Precio:<\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Para residentes en Suiza: A partir de 1300 CHF por semana. Para residentes internacionales: 1900CHF<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box16174_630dc0-85 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box16174_630dc0-85 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-top:0px;}.kt-info-box16174_630dc0-85 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box16174_630dc0-85 .kt-info-svg-icon-flip, .kt-info-box16174_630dc0-85 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box16174_630dc0-85 .kt-blocks-info-box-media{border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:0px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box16174_630dc0-85 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box16174_630dc0-85 .kt-infobox-textcontent h3.kt-blocks-info-box-title{letter-spacing:-0.7px;font-family:Nunito;font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box16174_630dc0-85 .kt-blocks-info-box-text{font-size:16px;line-height:21px;font-family:Nunito;font-style:normal;font-weight:400;padding-top:8px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box16174_630dc0-85 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 767px){.kt-info-box16174_630dc0-85 .kt-blocks-info-box-link-wrap{text-align:left;}.kt-info-box16174_630dc0-85 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:15px;}.wp-block-kadence-infobox.kt-info-box16174_630dc0-85 .kt-blocks-info-box-text{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box16174_630dc0-85\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong>Actividades incluidas:<\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Escalada, Deportes Acu\u00e1ticos, Acampada, Refugio de Monta\u00f1a, Taller de Supervivencia&#8230; \u00a1y mucho m\u00e1s!<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{display:flex;}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col,.kadence-column16174_6dc01c-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_6dc01c-91{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_6dc01c-91{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_6dc01c-91{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_6dc01c-91{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_6dc01c-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_6dc01c-91\"><div class=\"kt-inside-inner-col\"><style>.kb-image16174_78f8c5-fe.kb-image-is-ratio-size, .kb-image16174_78f8c5-fe .kb-image-is-ratio-size{max-width:640px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_78f8c5-fe.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_78f8c5-fe .kb-image-is-ratio-size{align-self:unset;}.kb-image16174_78f8c5-fe{max-width:640px;}.image-is-svg.kb-image16174_78f8c5-fe{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image16174_78f8c5-fe img{width:100%;}.kb-image16174_78f8c5-fe:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_78f8c5-fe.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image16174_78f8c5-fe .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image16174_78f8c5-fe:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_78f8c5-fe.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image16174_78f8c5-fe size-large\"><img decoding=\"async\" width=\"1024\" height=\"821\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage-1024x821.png\" alt=\"Summer camp Switzerland, International summer camp\" class=\"kb-img wp-image-46534\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage-1024x821.png 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage-150x120.png 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage-500x401.png 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage-768x616.png 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/WHOATourduMontBlancCollage.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id46916_6f46b9-fe > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id46916_6f46b9-fe > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id46916_6f46b9-fe > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46916_6f46b9-fe > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46916_6f46b9-fe > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46916_6f46b9-fe > .kt-row-column-wrap{row-gap:63px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46916_6f46b9-fe alignfull wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{padding-top:30px;padding-right:40px;padding-bottom:30px;padding-left:40px;}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{box-shadow:0px 0px 60px -20px #000000;}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col,.kadence-column46916_a80df6-b9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46916_a80df6-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46916_a80df6-b9{position:relative;}@media all and (max-width: 1024px){.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46916_a80df6-b9 > .kt-inside-inner-col{display:flex;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46916_a80df6-b9 kb-section-dir-vertical kb-section-sm-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id46916_464a70-96 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46916_464a70-96 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46916_464a70-96 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id46916_464a70-96 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46916_464a70-96 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46916_464a70-96 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46916_464a70-96 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col,.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46916_0a8e3d-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46916_0a8e3d-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46916_0a8e3d-eb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00, .wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00[data-kb-block=\"kb-adv-heading46916_4dcdad-00\"]{text-align:center;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00[data-kb-block=\"kb-adv-heading46916_4dcdad-00\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46916_4dcdad-00[data-kb-block=\"kb-adv-heading46916_4dcdad-00\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading46916_4dcdad-00 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading46916_4dcdad-00\">Campamento de verano Suiza: INSCRIPCI\u00d3N<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e, .wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e[data-kb-block=\"kb-adv-heading46916_197e68-6e\"]{text-align:center;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e[data-kb-block=\"kb-adv-heading46916_197e68-6e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e[data-kb-block=\"kb-adv-heading46916_197e68-6e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e, .wp-block-kadence-advancedheading.kt-adv-heading46916_197e68-6e[data-kb-block=\"kb-adv-heading46916_197e68-6e\"]{padding-bottom:0px;}}<\/style>\n<p class=\"kt-adv-heading46916_197e68-6e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading46916_197e68-6e\">\u00a1Res\u00e9rvate una plaza gratis!<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column46916_478929-f1 > .kt-inside-inner-col{display:flex;}.kadence-column46916_478929-f1 > .kt-inside-inner-col,.kadence-column46916_478929-f1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46916_478929-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column46916_478929-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column46916_478929-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column46916_478929-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46916_478929-f1{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column46916_478929-f1{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column46916_478929-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column46916_478929-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46916_478929-f1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns46916_289639-3d{padding-top:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column-reverse;align-items:center;justify-content:center;}.kt-btns46916_289639-3d .kt-button{font-weight:normal;font-style:normal;}.kt-btns46916_289639-3d .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46916_289639-3d .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns46916_289639-3d{padding-bottom:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns46916_289639-3d\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46916_a9df66-a4.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46916_a9df66-a4.kb-button{color:var(--global-palette3, #1A202C);font-size:16px;font-family:'Roboto Condensed';font-weight:600;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46916_a9df66-a4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46916_a9df66-a4.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46916_a9df66-a4.kb-button{font-size:14px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46916_a9df66-a4 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/inscripcion\/\"><span class=\"kt-btn-inner-text\">inscr\u00edbete aqu\u00ed<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_ae16a5-2a > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_ae16a5-2a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_ae16a5-2a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:40px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_ae16a5-2a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_ae16a5-2a > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_ae16a5-2a > .kt-row-column-wrap{padding-top:40px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_ae16a5-2a alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_c1d715-ca > .kt-inside-inner-col{display:flex;}.kadence-column16174_c1d715-ca > .kt-inside-inner-col,.kadence-column16174_c1d715-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_c1d715-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_c1d715-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_c1d715-ca{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_c1d715-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_c1d715-ca{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_c1d715-ca{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_c1d715-ca{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_c1d715-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_c1d715-ca\"><div class=\"kt-inside-inner-col\"><style>.kb-image16174_58e302-92.kb-image-is-ratio-size, .kb-image16174_58e302-92 .kb-image-is-ratio-size{max-width:640px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_58e302-92.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_58e302-92 .kb-image-is-ratio-size{align-self:unset;}.kb-image16174_58e302-92{max-width:640px;}.image-is-svg.kb-image16174_58e302-92{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image16174_58e302-92 img{width:100%;}.kb-image16174_58e302-92:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_58e302-92.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image16174_58e302-92 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image16174_58e302-92:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_58e302-92.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image16174_58e302-92 size-full\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2.jpg\" alt=\"Summer camp Switzerland, International summer camp\" class=\"kb-img wp-image-64230\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06993-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_fb314c-70 > .kt-inside-inner-col,.kadence-column16174_fb314c-70 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_fb314c-70 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_fb314c-70 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_fb314c-70 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_fb314c-70 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_fb314c-70{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_fb314c-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_fb314c-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_fb314c-70\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4, .wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4[data-kb-block=\"kb-adv-heading16174_d8625c-c4\"]{padding-right:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4[data-kb-block=\"kb-adv-heading16174_d8625c-c4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4[data-kb-block=\"kb-adv-heading16174_d8625c-c4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4, .wp-block-kadence-advancedheading.kt-adv-heading16174_d8625c-c4[data-kb-block=\"kb-adv-heading16174_d8625c-c4\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_d8625c-c4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_d8625c-c4\">El campamento de un vistazo:<\/h2>\n\n\n<style>.kadence-column16174_82965f-58 > .kt-inside-inner-col,.kadence-column16174_82965f-58 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_82965f-58 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_82965f-58 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_82965f-58 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_82965f-58 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_82965f-58{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_82965f-58 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_82965f-58 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_82965f-58\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-16174_494754-a2 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_494754-a2 .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_494754-a2 .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_494754-a2\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_81e37b-59 > .kt-inside-inner-col,.kadence-column16174_81e37b-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_81e37b-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_81e37b-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_81e37b-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_81e37b-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_81e37b-59{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_81e37b-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_81e37b-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_81e37b-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a, .wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a[data-kb-block=\"kb-adv-heading16174_e919a3-1a\"]{padding-right:0px;padding-left:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a[data-kb-block=\"kb-adv-heading16174_e919a3-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a[data-kb-block=\"kb-adv-heading16174_e919a3-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a, .wp-block-kadence-advancedheading.kt-adv-heading16174_e919a3-1a[data-kb-block=\"kb-adv-heading16174_e919a3-1a\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_e919a3-1a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_e919a3-1a\">El campamento de verano de senderismo: Tour du Mont Blanc para adolescentes es una m\u00edtica e impresionante excursi\u00f3n de 7 d\u00edas alrededor del Mont Blanc macizo de los Alpes. Amigable para los ni\u00f1os, lo que significa d\u00edas cortos y subidas menos empinadas, la ruta ofrece la oportunidad de sumergirse en el rico patrimonio natural de la zona. Caminaremos todos los d\u00edas unas 4 horas, dormiremos en tiendas y refugios de monta\u00f1a, construiremos campamentos, participaremos en actividades vespertinas y aprenderemos datos \u00fanicos sobre geolog\u00eda, biolog\u00eda y astronom\u00eda.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_e3744c-14{padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_e3744c-14 .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_e3744c-14 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_e3744c-14 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_e3744c-14{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_e3744c-14\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_5ca35b-6a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_5ca35b-6a.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_5ca35b-6a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_5ca35b-6a.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_5ca35b-6a.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_5ca35b-6a kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"\/leadership-program\/\"><span class=\"kt-btn-inner-text\">\u00bfPrefieres un campamento residencial? Consulta nuestro CAMPAMENTO Multiaventura para Mayores<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:40px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_6e5c0f-a1 > .kt-row-column-wrap{padding-top:40px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_6e5c0f-a1 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_04af8b-e6 > .kt-inside-inner-col,.kadence-column16174_04af8b-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_04af8b-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_04af8b-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_04af8b-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_04af8b-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_04af8b-e6{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_04af8b-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_04af8b-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_04af8b-e6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da, .wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da[data-kb-block=\"kb-adv-heading16174_cf4666-da\"]{padding-right:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da[data-kb-block=\"kb-adv-heading16174_cf4666-da\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da[data-kb-block=\"kb-adv-heading16174_cf4666-da\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da, .wp-block-kadence-advancedheading.kt-adv-heading16174_cf4666-da[data-kb-block=\"kb-adv-heading16174_cf4666-da\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_cf4666-da wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_cf4666-da\">Un c\u00f3ctel de actividades para todos los gustos<\/h2>\n\n\n<style>.kadence-column16174_3b6330-53 > .kt-inside-inner-col,.kadence-column16174_3b6330-53 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_3b6330-53 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_3b6330-53 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_3b6330-53 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_3b6330-53 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_3b6330-53{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_3b6330-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_3b6330-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_3b6330-53\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-16174_05515e-95 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_05515e-95 .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_05515e-95 .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_05515e-95\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_f38d59-f5 > .kt-inside-inner-col,.kadence-column16174_f38d59-f5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_f38d59-f5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_f38d59-f5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_f38d59-f5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_f38d59-f5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_f38d59-f5{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_f38d59-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_f38d59-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_f38d59-f5\"><div class=\"kt-inside-inner-col\">\n<ul style=\"padding-right:20px;padding-left:20px\" class=\"wp-block-list has-18-14-font-size\">\n<li><strong>Ma\u00f1anas de Senderismo<\/strong>: Conquista los senderos emblem\u00e1ticos, supervisado por nuestros gu\u00edas experimentados.<\/li>\n\n\n\n<li>Cada d\u00eda ofrece un nuevo descubrimiento, desde el amanecer sobre picos nevados hasta cruzar valles llenos de flores.<\/li>\n\n\n\n<li><strong>Tardes multideporte<\/strong>: Tras un d\u00eda en la monta\u00f1a, \u00a1las tardes se dedican a diversas actividades deportivas!<\/li>\n\n\n\n<li><strong>Las tardes<\/strong> est\u00e1n reservadas a los juegos de equipo: imagina competiciones de construcci\u00f3n de balsas, donde la cooperaci\u00f3n y el ingenio ser\u00e1n tus mejores aliados para navegar por las tranquilas aguas de un lago de monta\u00f1a. Las tardes se animan con desaf\u00edos nocturnos de orientaci\u00f3n, que fomentan la confianza y la colaboraci\u00f3n bajo un cielo estrellado. <\/li>\n<\/ul>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_61f528-07 > .kt-inside-inner-col{display:flex;}.kadence-column16174_61f528-07 > .kt-inside-inner-col,.kadence-column16174_61f528-07 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_61f528-07 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_61f528-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_61f528-07{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_61f528-07 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_61f528-07{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_61f528-07{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_61f528-07{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_61f528-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_61f528-07\"><div class=\"kt-inside-inner-col\"><style>.kb-image16174_b0a9b8-c4.kb-image-is-ratio-size, .kb-image16174_b0a9b8-c4 .kb-image-is-ratio-size{max-width:640px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_b0a9b8-c4.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_b0a9b8-c4 .kb-image-is-ratio-size{align-self:unset;}.kb-image16174_b0a9b8-c4{max-width:640px;}.image-is-svg.kb-image16174_b0a9b8-c4{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image16174_b0a9b8-c4 img{width:100%;}.kb-image16174_b0a9b8-c4:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_b0a9b8-c4.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image16174_b0a9b8-c4 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image16174_b0a9b8-c4:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_b0a9b8-c4.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image16174_b0a9b8-c4 size-full\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg\" alt=\"Summer camp Switzerland, International summer camp\" class=\"kb-img wp-image-64221\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:40px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_fd02a0-3c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap{padding-top:20px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id16174_fd02a0-3c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_fd02a0-3c alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_cc5908-ae > .kt-inside-inner-col{display:flex;}.kadence-column16174_cc5908-ae > .kt-inside-inner-col,.kadence-column16174_cc5908-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_cc5908-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_cc5908-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_cc5908-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_cc5908-ae{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_cc5908-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_cc5908-ae{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_cc5908-ae{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_cc5908-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_cc5908-ae > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column16174_cc5908-ae{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_cc5908-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_cc5908-ae\"><div class=\"kt-inside-inner-col\"><style>.kb-image16174_705d8a-1f.kb-image-is-ratio-size, .kb-image16174_705d8a-1f .kb-image-is-ratio-size{max-width:640px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_705d8a-1f.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_705d8a-1f .kb-image-is-ratio-size{align-self:unset;}.kb-image16174_705d8a-1f{max-width:640px;}.image-is-svg.kb-image16174_705d8a-1f{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image16174_705d8a-1f img{width:100%;}.kb-image16174_705d8a-1f:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_705d8a-1f.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image16174_705d8a-1f .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image16174_705d8a-1f:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_705d8a-1f.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image16174_705d8a-1f size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-1024x768.jpg\" alt=\"Summer camp Switzerland, International summer camp\" class=\"kb-img wp-image-64930\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1-1536x1152.jpg 1536w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9616-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_f71af8-2a > .kt-inside-inner-col,.kadence-column16174_f71af8-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_f71af8-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_f71af8-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_f71af8-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_f71af8-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_f71af8-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_f71af8-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_f71af8-2a > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_f71af8-2a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1, .wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1[data-kb-block=\"kb-adv-heading16174_09541b-e1\"]{padding-right:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1[data-kb-block=\"kb-adv-heading16174_09541b-e1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1[data-kb-block=\"kb-adv-heading16174_09541b-e1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1, .wp-block-kadence-advancedheading.kt-adv-heading16174_09541b-e1[data-kb-block=\"kb-adv-heading16174_09541b-e1\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_09541b-e1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_09541b-e1\">Biling\u00fce e Internacional: Ingl\u00e9s y franc\u00e9s<\/h2>\n\n\n<style>.kadence-column16174_b2425d-3c > .kt-inside-inner-col,.kadence-column16174_b2425d-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_b2425d-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_b2425d-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_b2425d-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_b2425d-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_b2425d-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_b2425d-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_b2425d-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_b2425d-3c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-16174_dbc1cb-8c .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_dbc1cb-8c .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_dbc1cb-8c .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_dbc1cb-8c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_35a926-90 > .kt-inside-inner-col,.kadence-column16174_35a926-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_35a926-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_35a926-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_35a926-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_35a926-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_35a926-90{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_35a926-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_35a926-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_35a926-90\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9, .wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9[data-kb-block=\"kb-adv-heading16174_966e6d-e9\"]{padding-right:0px;padding-left:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9[data-kb-block=\"kb-adv-heading16174_966e6d-e9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9[data-kb-block=\"kb-adv-heading16174_966e6d-e9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9, .wp-block-kadence-advancedheading.kt-adv-heading16174_966e6d-e9[data-kb-block=\"kb-adv-heading16174_966e6d-e9\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_966e6d-e9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_966e6d-e9\">El Young Explorers Club<mark class=\"kt-highlight\"> <\/mark>El campamento de verano acoge a participantes internacionales y suizos en un entorno biling\u00fce y multicultural. Nuestras actividades se desarrollan principalmente en ingl\u00e9s, pero tambi\u00e9n se integra el franc\u00e9s, lo que permite que todos los ni\u00f1os se sientan incluidos.<br\/><br\/>Nuestro equipo habla varios idiomas (ingl\u00e9s, franc\u00e9s, alem\u00e1n y otros), lo que crea un entorno de apoyo, tanto si tu hijo domina el ingl\u00e9s como si est\u00e1 empezando a aprenderlo.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_94a08b-fc{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_94a08b-fc .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_94a08b-fc .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_94a08b-fc .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_94a08b-fc{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_94a08b-fc\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_bff834-fb.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_bff834-fb.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_bff834-fb.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_bff834-fb.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_bff834-fb.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_bff834-fb kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/presentacion-del-club\/\"><span class=\"kt-btn-inner-text\">El Club: Su historia<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_f0f021-50 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_f0f021-50 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_f0f021-50 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:60px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_f0f021-50 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_f0f021-50 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_f0f021-50 > .kt-row-column-wrap{padding-top:20px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_f0f021-50 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col,.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_c1d1dc-05{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_c1d1dc-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_c1d1dc-05\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd, .wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd[data-kb-block=\"kb-adv-heading16174_1c1fa0-dd\"]{padding-right:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd[data-kb-block=\"kb-adv-heading16174_1c1fa0-dd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd[data-kb-block=\"kb-adv-heading16174_1c1fa0-dd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd, .wp-block-kadence-advancedheading.kt-adv-heading16174_1c1fa0-dd[data-kb-block=\"kb-adv-heading16174_1c1fa0-dd\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_1c1fa0-dd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_1c1fa0-dd\">Un programa variado y lleno de acci\u00f3n<\/h2>\n\n\n<style>.kadence-column16174_4f7832-cb > .kt-inside-inner-col,.kadence-column16174_4f7832-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_4f7832-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_4f7832-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_4f7832-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_4f7832-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_4f7832-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_4f7832-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_4f7832-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_4f7832-cb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-16174_249f3e-ff .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_249f3e-ff .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_249f3e-ff .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_249f3e-ff\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_e8cc18-dd > .kt-inside-inner-col,.kadence-column16174_e8cc18-dd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_e8cc18-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_e8cc18-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_e8cc18-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_e8cc18-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_e8cc18-dd{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_e8cc18-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_e8cc18-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_e8cc18-dd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72, .wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72[data-kb-block=\"kb-adv-heading16174_e31111-72\"]{padding-right:0px;padding-left:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72[data-kb-block=\"kb-adv-heading16174_e31111-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72[data-kb-block=\"kb-adv-heading16174_e31111-72\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72, .wp-block-kadence-advancedheading.kt-adv-heading16174_e31111-72[data-kb-block=\"kb-adv-heading16174_e31111-72\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_e31111-72 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_e31111-72\">En el Campamento creemos en el aprendizaje experimental y en la importancia de comprender y preservar nuestro entorno natural. Por eso ofrecemos una variedad de talleres educativos que enriquecen tu experiencia al aire libre:<br\/><\/p>\n\n\n\n<ul style=\"padding-right:20px;padding-left:20px\" class=\"wp-block-list has-18-14-font-size\">\n<li>Talleres sobre Fauna y Flora.<\/li>\n\n\n\n<li>T\u00e9cnicas de Supervivencia al Aire Libre.<\/li>\n\n\n\n<li>Preservaci\u00f3n del Medio Ambiente.<\/li>\n<\/ul>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_ebe458-56{padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_ebe458-56 .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_ebe458-56 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_ebe458-56 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_ebe458-56{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_ebe458-56\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_39c35d-dd.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_39c35d-dd.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_39c35d-dd.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_39c35d-dd.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_39c35d-dd.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_39c35d-dd kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/nuestra-filosofia\/\"><span class=\"kt-btn-inner-text\">Nuestra filosof\u00eda<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_0b7622-5a > .kt-inside-inner-col{display:flex;}.kadence-column16174_0b7622-5a > .kt-inside-inner-col,.kadence-column16174_0b7622-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_0b7622-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_0b7622-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_0b7622-5a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_0b7622-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_0b7622-5a{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_0b7622-5a{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_0b7622-5a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_0b7622-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_0b7622-5a\"><div class=\"kt-inside-inner-col\"><style>.kb-image16174_e9a188-f1.kb-image-is-ratio-size, .kb-image16174_e9a188-f1 .kb-image-is-ratio-size{max-width:640px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_e9a188-f1.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image16174_e9a188-f1 .kb-image-is-ratio-size{align-self:unset;}.kb-image16174_e9a188-f1{max-width:640px;}.image-is-svg.kb-image16174_e9a188-f1{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image16174_e9a188-f1 img{width:100%;}.kb-image16174_e9a188-f1:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_e9a188-f1.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image16174_e9a188-f1 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.kb-image16174_e9a188-f1:not(.kb-image-is-ratio-size) .kb-img, .kb-image16174_e9a188-f1.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image16174_e9a188-f1 size-full\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg\" alt=\"Summer camp Switzerland, International summer camp\" class=\"kb-img wp-image-64224\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_1adaad-17 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_1adaad-17 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_1adaad-17 > .kt-row-column-wrap{column-gap:50px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:40px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id16174_1adaad-17 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_1adaad-17 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id16174_1adaad-17 > .kt-row-column-wrap{padding-top:40px;padding-right:20px;padding-bottom:40px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_1adaad-17 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_a8021a-4d > .kt-inside-inner-col{display:flex;}.kadence-column16174_a8021a-4d > .kt-inside-inner-col,.kadence-column16174_a8021a-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_a8021a-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_a8021a-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_a8021a-4d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_a8021a-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_a8021a-4d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_a8021a-4d{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_a8021a-4d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_a8021a-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_a8021a-4d\"><div class=\"kt-inside-inner-col\"><style>.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{padding-top:48px;padding-right:22px;padding-bottom:20px;padding-left:22px;}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col,.kadence-column16174_0fe433-c4 > .kt-inside-inner-col:before{border-top-left-radius:7px;border-top-right-radius:7px;border-bottom-right-radius:7px;border-bottom-left-radius:7px;}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{background-color:rgba(248, 156, 0, 0.1);}.kadence-column16174_0fe433-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_0fe433-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_0fe433-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_0fe433-c4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0, .wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0[data-kb-block=\"kb-adv-heading16174_df0482-c0\"]{margin-bottom:10px;text-align:center;font-size:22px;line-height:1;font-weight:400;font-style:normal;font-family:Roboto;text-transform:capitalize;color:#000000;}.wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0[data-kb-block=\"kb-adv-heading16174_df0482-c0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0[data-kb-block=\"kb-adv-heading16174_df0482-c0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0, .wp-block-kadence-advancedheading.kt-adv-heading16174_df0482-c0[data-kb-block=\"kb-adv-heading16174_df0482-c0\"]{font-size:17px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_df0482-c0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_df0482-c0\">Residentes en Suiza:<\/h2>\n\n\n<style>.kadence-column16174_b42228-94 > .kt-inside-inner-col{display:flex;}.kadence-column16174_b42228-94 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col,.kadence-column16174_b42228-94 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col{column-gap:5px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;justify-content:center;}.kadence-column16174_b42228-94 > .kt-inside-inner-col > *, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column16174_b42228-94 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_b42228-94{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_b42228-94 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;justify-content:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column16174_b42228-94 > .kt-inside-inner-col > *, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column16174_b42228-94 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:center;}.kadence-column16174_b42228-94 > .kt-inside-inner-col > *, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_b42228-94 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_b42228-94 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_b42228-94 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has--font-size has-52-17-font-size\">AHORA 1300 chf<\/h2>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_5b8445-b2{padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_5b8445-b2 .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_5b8445-b2 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_5b8445-b2 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_5b8445-b2{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_5b8445-b2\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_e79489-53.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_e79489-53.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_e79489-53.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_e79489-53.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_e79489-53.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_e79489-53 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/inscripcion\/\"><span class=\"kt-btn-inner-text\">INSCRIPCIONES gratuitas aqu\u00ed  <\/span><\/a><\/div>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list{grid-row-gap:3px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0 .kb-svg-icon-wrap{font-size:13px;color:var(--global-palette9, #ffffff);}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette4, #2D3748);letter-spacing:0.1px;color:var(--global-palette4, #2D3748);}.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-single{background-color:#dd9933;border-radius:50%;border-color:#dd9933;border-width:2px;border-style:solid;padding:1px;}@media all and (max-width: 767px){.kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items16174_d7a4c8-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items16174_d7a4c8-b0 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-16174_fd4ca9-aa .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_fd4ca9-aa\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Precio por semana.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_472051-ca .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_472051-ca .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_472051-ca\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Descuento para grupos (2+): 10% DESCUENTO.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_40c8c7-d8 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_40c8c7-d8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_40c8c7-d8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Todo incluido: Actividades, Alojamiento, Comida, Excursiones, etc.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_3754db-d2 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_3754db-d2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_3754db-d2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pago <strong>a plazos disponible.<\/strong><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_864652-3e .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_864652-3e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_864652-3e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Comidas con opciones flexibles.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_203c9f-d3 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_203c9f-d3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_203c9f-d3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fechas de participaci\u00f3n flexibles. (D\u00edas de inicio y salidas)<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column16174_452154-a0 > .kt-inside-inner-col,.kadence-column16174_452154-a0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_452154-a0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_452154-a0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_452154-a0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_452154-a0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_452154-a0{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_452154-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_452154-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_452154-a0\"><div class=\"kt-inside-inner-col\"><style>.kadence-column16174_718095-3b > .kt-inside-inner-col{display:flex;}.kadence-column16174_718095-3b > .kt-inside-inner-col{padding-top:48px;padding-right:22px;padding-bottom:20px;padding-left:22px;}.kadence-column16174_718095-3b > .kt-inside-inner-col,.kadence-column16174_718095-3b > .kt-inside-inner-col:before{border-top-left-radius:7px;border-top-right-radius:7px;border-bottom-right-radius:7px;border-bottom-left-radius:7px;}.kadence-column16174_718095-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_718095-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_718095-3b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_718095-3b > .kt-inside-inner-col{background-color:rgba(248, 156, 0, 0.1);}.kadence-column16174_718095-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_718095-3b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_718095-3b{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column16174_718095-3b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column16174_718095-3b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_718095-3b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87, .wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87[data-kb-block=\"kb-adv-heading16174_77fa27-87\"]{margin-bottom:10px;text-align:center;font-size:22px;line-height:1;font-weight:400;font-style:normal;font-family:Roboto;text-transform:capitalize;color:#000000;}.wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87[data-kb-block=\"kb-adv-heading16174_77fa27-87\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87[data-kb-block=\"kb-adv-heading16174_77fa27-87\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87, .wp-block-kadence-advancedheading.kt-adv-heading16174_77fa27-87[data-kb-block=\"kb-adv-heading16174_77fa27-87\"]{font-size:17px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_77fa27-87 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_77fa27-87\">Participantes internacionales:<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39, .wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39[data-kb-block=\"kb-adv-heading16174_09d2b3-39\"]{margin-bottom:5px;text-align:center;font-size:18px;line-height:1;font-weight:300;font-style:normal;font-family:Roboto;text-transform:capitalize;color:#000000;}.wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39[data-kb-block=\"kb-adv-heading16174_09d2b3-39\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39[data-kb-block=\"kb-adv-heading16174_09d2b3-39\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39, .wp-block-kadence-advancedheading.kt-adv-heading16174_09d2b3-39[data-kb-block=\"kb-adv-heading16174_09d2b3-39\"]{font-size:15px;}}<\/style>\n<h2 class=\"kt-adv-heading16174_09d2b3-39 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_09d2b3-39\">1 CHF \u2248 1,1 EUR \/ USD<\/h2>\n\n\n<style>.kadence-column16174_83557c-cf > .kt-inside-inner-col{display:flex;}.kadence-column16174_83557c-cf > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col,.kadence-column16174_83557c-cf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col{column-gap:5px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;justify-content:center;}.kadence-column16174_83557c-cf > .kt-inside-inner-col > *, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column16174_83557c-cf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_83557c-cf{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_83557c-cf > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;justify-content:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column16174_83557c-cf > .kt-inside-inner-col > *, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column16174_83557c-cf > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:center;}.kadence-column16174_83557c-cf > .kt-inside-inner-col > *, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-image, .kadence-column16174_83557c-cf > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column16174_83557c-cf > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_83557c-cf kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has--font-size has-52-17-font-size\">AHORA 1900 chf<\/h2>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_8ddbf4-8f{padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_8ddbf4-8f .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_8ddbf4-8f .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_8ddbf4-8f{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_8ddbf4-8f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_45019d-0a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_45019d-0a.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_45019d-0a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_45019d-0a.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_45019d-0a.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_45019d-0a kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/inscripcion\/\"><span class=\"kt-btn-inner-text\">INSCRIPCIONES gratuitas aqu\u00ed  <\/span><\/a><\/div>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list{grid-row-gap:3px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32 .kb-svg-icon-wrap{font-size:13px;color:var(--global-palette1, #3182CE);}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette4, #2D3748);letter-spacing:0.1px;color:var(--global-palette4, #2D3748);}.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-single{background-color:#dd9933;border-radius:50%;border-color:#dd9933;border-width:2px;border-style:solid;padding:1px;}@media all and (max-width: 767px){.kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items16174_7450c0-32 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:15px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items16174_7450c0-32 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-16174_dfa74e-41 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_dfa74e-41\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Precio por semana.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_756c7f-37 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_756c7f-37 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_756c7f-37\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Descuento para grupos (2+): 10% DESCUENTO.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_7aebf7-06 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_7aebf7-06 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_7aebf7-06\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Todo incluido: Actividades, Alojamiento, Comida, Equipamiento, etc.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_41aa14-8c .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_41aa14-8c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_41aa14-8c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>Transporte al aeropuerto:<\/strong> Transporte desde \/ hasta<strong> el AEROPUERTO DE GINEBRA<\/strong> Incluido.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_fa0dd7-e3 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_fa0dd7-e3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_fa0dd7-e3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pago <strong>a plazos disponible.<\/strong><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_74131f-6c .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_74131f-6c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_74131f-6c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Bicicleta, saco de dormir y dem\u00e1s equipamiento incluidos.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_99c8c5-a5 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_99c8c5-a5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_99c8c5-a5\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Comidas con opciones flexibles.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-16174_eca175-61 .kt-svg-icon-list-single{color:var(--global-palette9, #ffffff) !important;}.kt-svg-icon-list-item-16174_eca175-61 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-16174_eca175-61\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fechas de participaci\u00f3n flexibles. (D\u00edas de inicio y salidas).<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{display:flex;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:0px;padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:0px;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col,.kadence-column16174_ac64ec-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column16174_ac64ec-79{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{background-color:rgba(248, 156, 0, 0.17);}.kadence-column16174_ac64ec-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_ac64ec-79{text-align:center;}.kadence-column16174_ac64ec-79{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column16174_ac64ec-79{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{padding-top:30px;padding-right:10px;padding-bottom:30px;padding-left:10px;flex-direction:column;justify-content:center;align-items:center;}.kt-row-column-wrap > .kadence-column16174_ac64ec-79{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column16174_ac64ec-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_ac64ec-79\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78, .wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78[data-kb-block=\"kb-adv-heading16174_bafeda-78\"]{font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78[data-kb-block=\"kb-adv-heading16174_bafeda-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_bafeda-78[data-kb-block=\"kb-adv-heading16174_bafeda-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading16174_bafeda-78 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_bafeda-78\"><strong><strong><strong>M\u00e1s informaci\u00f3n y detalles:<\/strong><\/strong><\/strong><\/h2>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-16174_12aeae-cb .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-16174_12aeae-cb .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-16174_12aeae-cb .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-16174_12aeae-cb\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n<style>.kb-row-layout-id16174_ef120f-ad > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_ef120f-ad > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_ef120f-ad > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:25px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_ef120f-ad > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_ef120f-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id16174_ef120f-ad > .kt-row-column-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_ef120f-ad alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_77af95-01 > .kt-inside-inner-col,.kadence-column16174_77af95-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_77af95-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_77af95-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_77af95-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_77af95-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_77af95-01{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_77af95-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_77af95-01 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_77af95-01\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id16174_682d16-66 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:17px;}.kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f7f7f9;font-size:15px;line-height:24px;letter-spacing:0px;font-family:Nunito;font-weight:700;text-transform:capitalize;color:#000000;padding-top:13px;padding-right:20px;padding-bottom:13px;padding-left:20px;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#000000;}.kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h1, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h2, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h3, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h4, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h5, .kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner h6{color:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f7f7f9;}.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66 .kt-blocks-accordion-header:focus-visible{color:#000000;background:var(--global-palette1, #3182CE);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id16174_682d16-66 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#000000;background:var(--global-palette1, #3182CE);border-top:0px solid var(--global-palette9, #ffffff);border-right:0px solid var(--global-palette9, #ffffff);border-bottom:0px solid var(--global-palette9, #ffffff);border-left:0px solid var(--global-palette9, #ffffff);}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#000000;}.kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id16174_682d16-66:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id16174_682d16-66 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:0px solid var(--global-palette9, #ffffff);border-right:0px solid var(--global-palette9, #ffffff);border-bottom:0px solid var(--global-palette9, #ffffff);border-left:0px solid var(--global-palette9, #ffffff);}}@media all and (max-width: 767px){.kt-accordion-id16174_682d16-66 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id16174_682d16-66 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:17px;}.kt-accordion-id16174_682d16-66 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;font-size:14px;}.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id16174_682d16-66 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id16174_682d16-66 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id16174_682d16-66 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:0px solid var(--global-palette9, #ffffff);border-right:0px solid var(--global-palette9, #ffffff);border-bottom:0px solid var(--global-palette9, #ffffff);border-left:0px solid var(--global-palette9, #ffffff);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id16174_682d16-66 kt-accordion-has-9-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-none kt-accodion-icon-side-right\" style=\"max-width:1300px\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane16174_ee9a99-09\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fechas:<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c, .wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c[data-kb-block=\"kb-adv-heading16174_e67b3f-5c\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c[data-kb-block=\"kb-adv-heading16174_e67b3f-5c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c[data-kb-block=\"kb-adv-heading16174_e67b3f-5c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c, .wp-block-kadence-advancedheading.kt-adv-heading16174_e67b3f-5c[data-kb-block=\"kb-adv-heading16174_e67b3f-5c\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_e67b3f-5c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_e67b3f-5c\"><strong>Fechas:<\/strong><br\/><strong>Sesi\u00f3n 1:<\/strong> 26.07.26 &#8211; 1.08.26<br\/><strong>Sesi\u00f3n 2:<\/strong> 9.08.26 &#8211; 15.08.26<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane16174_86e432-5c\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Precios<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6, .wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6[data-kb-block=\"kb-adv-heading16174_390881-b6\"]{text-align:left;font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6[data-kb-block=\"kb-adv-heading16174_390881-b6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6[data-kb-block=\"kb-adv-heading16174_390881-b6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6, .wp-block-kadence-advancedheading.kt-adv-heading16174_390881-b6[data-kb-block=\"kb-adv-heading16174_390881-b6\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_390881-b6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_390881-b6\">El campamento se desarrolla en sesiones independientes de 1 semana (aunque recomendamos la participaci\u00f3n durante varias semanas, ya que el programa var\u00eda y esto es lo que hace la mayor\u00eda de los participantes). A continuaci\u00f3n encontrar\u00e1s los <strong>descuentos<\/strong> para grupos y familias <strong><u><em><strong>.<\/strong><\/em><\/u><br\/><\/strong><br\/> <br\/><strong>Precio (por semana y participante):<\/strong><br\/> <br\/>Participante suizo: <strong>1300CHF**<\/strong>. Participante internacional: <strong>1900CHF**<\/strong>. <br\/> <br\/> <br\/><strong>M\u00e1s detalles:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/><strong>* Los participantes pueden llegar o salir del campamento en fechas ligeramente diferentes (dependiendo de la log\u00edstica y la ubicaci\u00f3n), ponte en contacto con nosotros para obtener m\u00e1s informaci\u00f3n.  <\/strong>Los asistentes pueden participar en una o varias sesiones consecutivas.<br\/>Y para quienes deseen campamentos m\u00e1s largos, tambi\u00e9n tenemos otros campamentos (es posible participar en varias sesiones).<br\/> <br\/>**Gracias a la ayuda de nuestros patrocinadores locales, podemos ofrecer un precio reducido a todos los ciudadanos suizos.<br\/>El precio mencionado incluye <strong>todos los gastos del participante<\/strong> durante el periodo del campamento, es decir, todo el transporte p\u00fablico o privado durante el campamento, la comida, los gastos de alojamiento y cualquier equipo com\u00fan del grupo (tiendas de campa\u00f1a y cualquier otro equipo relacionado con las actividades, arn\u00e9s y equipo de Escalada).<br\/>No incluye: Transporte de ida y vuelta al punto de encuentro y cualquier equipamiento personal (saco de dormir (contacta con nosotros si lo necesitas), ropa y otros gastos personales).<br\/> <br\/><strong>DESCUENTOS PARA FAMILIAS\/GRUPOS<\/strong>: Con el fin de promocionar el campamento entre un mayor n\u00famero de familias (que tambi\u00e9n podr\u00edan compartir nuestros valores), podemos ofrecer un 10% de descuento en todas las reservas si se unen a un amigo o familiar. Esto significa que si inscribes a dos o m\u00e1s participantes, cada una de esas inscripciones ser\u00e1 un 10% m\u00e1s barata.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane16174_8012af-fe\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Ages &amp; Languages<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0, .wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0[data-kb-block=\"kb-adv-heading16174_96e6c4-f0\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0[data-kb-block=\"kb-adv-heading16174_96e6c4-f0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0[data-kb-block=\"kb-adv-heading16174_96e6c4-f0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0, .wp-block-kadence-advancedheading.kt-adv-heading16174_96e6c4-f0[data-kb-block=\"kb-adv-heading16174_96e6c4-f0\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_96e6c4-f0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_96e6c4-f0\">Ofrecemos este campamento para familias con hijos de 13* a 17 a\u00f1os (itinerario y actividades adaptados a las necesidades).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/><strong>Creemos en reunir a una comunidad internacional, por eso las lenguas que se hablan en el campamento son el franc\u00e9s y el ingl\u00e9s, que es lo que hemos comprobado en nuestra experiencia pasada y el enorme beneficio que supone mezclar franc\u00f3fonos y angl\u00f3fonos y aprender de ambos grupos.<\/strong><br\/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*\u00bfMenores de 13 a\u00f1os? A nuestra discreci\u00f3n y si los participantes est\u00e1n especialmente en forma y motivados, permitimos excepciones de edad, ponte en contacto con nosotros para obtener m\u00e1s informaci\u00f3n.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane16174_99b7b0-bb\"><h3 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Punto de encuentro<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h3><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67, .wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67[data-kb-block=\"kb-adv-heading16174_36cd2f-67\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67[data-kb-block=\"kb-adv-heading16174_36cd2f-67\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67[data-kb-block=\"kb-adv-heading16174_36cd2f-67\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67, .wp-block-kadence-advancedheading.kt-adv-heading16174_36cd2f-67[data-kb-block=\"kb-adv-heading16174_36cd2f-67\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_36cd2f-67 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_36cd2f-67\">Para los participantes suizos, el punto de encuentro para las distintas sesiones de los campamentos es la estaci\u00f3n de tren de Lausana. Desde Lausana, se organiza el transporte hasta la salida del campamento. Se organizar\u00e1 otro punto de encuentro desde el aeropuerto de Ginebra para los participantes internacionales (incluido en el precio). Tambi\u00e9n es posible traer al participante directamente a nuestros chalets de Les Diablerets.<br\/><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-10 kt-pane16174_101821-f4\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfPor qu\u00e9 deber\u00eda asistir a este campamento?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1, .wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1[data-kb-block=\"kb-adv-heading16174_11afe8-d1\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1[data-kb-block=\"kb-adv-heading16174_11afe8-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1[data-kb-block=\"kb-adv-heading16174_11afe8-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1, .wp-block-kadence-advancedheading.kt-adv-heading16174_11afe8-d1[data-kb-block=\"kb-adv-heading16174_11afe8-d1\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_11afe8-d1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_11afe8-d1\">Participar en el campamento de verano &#8220;Tour du Mont Blanc&#8221; es una experiencia incomparable que combina aventura, aprendizaje y descubrimiento personal en uno de los entornos monta\u00f1osos m\u00e1s espectaculares del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Es una oportunidad para sumergirte en la impresionante belleza natural, desafiarte f\u00edsicamente haciendo senderismo por el Mont Blanc macizo, y desarrollar habilidades de liderazgo y trabajo en equipo mediante diversas actividades.<br\/>Tambi\u00e9n tendr\u00e1s la oportunidad de conocer a j\u00f3venes de diversos or\u00edgenes, lo que enriquecer\u00e1 tu experiencia mediante el intercambio cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Este campamento ofrece mucho m\u00e1s que una aventura: es una b\u00fasqueda de crecimiento personal, independencia y recuerdos que durar\u00e1n toda la vida.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-11 kt-pane16174_1f2697-5c\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Itinerario y actividades<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11, .wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11[data-kb-block=\"kb-adv-heading16174_adfc1a-11\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11[data-kb-block=\"kb-adv-heading16174_adfc1a-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11[data-kb-block=\"kb-adv-heading16174_adfc1a-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11, .wp-block-kadence-advancedheading.kt-adv-heading16174_adfc1a-11[data-kb-block=\"kb-adv-heading16174_adfc1a-11\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_adfc1a-11 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_adfc1a-11\">Nuestro <strong>Programa de Actividades<\/strong> evoluciona cada a\u00f1o para mantenerse fresco, emocionante y significativo. Mejoramos continuamente el horario, introducimos nuevas experiencias y perfeccionamos nuestros talleres bas\u00e1ndonos en los comentarios de los campistas y las familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>\ud83d\udc49 <strong>Para ver el programa m\u00e1s actualizado y detallado, consulta el <em>Folleto 2026<\/em><\/strong>, que describe el horario semanal completo, las opciones de actividades y los aspectos especiales m\u00e1s destacados del pr\u00f3ximo verano.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_d0a8f4-1f{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns16174_d0a8f4-1f .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_d0a8f4-1f .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_d0a8f4-1f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_6f100f-c7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_6f100f-c7.kb-button{color:var(--global-palette3, #1A202C);font-size:16px;font-family:'Roboto Condensed';font-weight:600;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_6f100f-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_6f100f-c7.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_6f100f-c7.kb-button{font-size:8px;letter-spacing:-0.01px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_6f100f-c7 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/pagina-del-formulario-del-folleto\/\"><span class=\"kt-btn-inner-text\">CONSIGUE EL FOLLETO AHORA<\/span><\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65, .wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65[data-kb-block=\"kb-adv-heading16174_d130b1-65\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65[data-kb-block=\"kb-adv-heading16174_d130b1-65\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65[data-kb-block=\"kb-adv-heading16174_d130b1-65\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65, .wp-block-kadence-advancedheading.kt-adv-heading16174_d130b1-65[data-kb-block=\"kb-adv-heading16174_d130b1-65\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_d130b1-65 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_d130b1-65\"><strong>D\u00eda 1: De Chamonix a Trient<\/strong><br\/>Nos embarcamos en una encantadora aventura que parte del pintoresco pueblo de Le Tour, iniciando un ascenso a trav\u00e9s de los verdes pastos de monta\u00f1a para llegar al Col de Balme (2191 m), situado en la frontera franco-suiza. Desde aqu\u00ed disfrutamos de una \u00faltima mirada al hermoso valle de Chamonix y al imponente macizo de las Agujas Rojas antes de descender a trav\u00e9s de verdes pastos y densos bosques, para llegar finalmente al encantador pueblo de Trient (1326 m). Pasaremos la noche en el pintoresco camping del Col de la Forclaz.  <br\/>Desnivel: 600 m, desnivel: 600 m<br\/> <br\/><strong>D\u00eda 2: Trient en La Fouly<\/strong><br\/>Escalada por un frondoso bosque que domina el valle del R\u00f3dano y Martigny, llegamos a los apacibles pastos de monta\u00f1a de La Bovine (1987 m), un lugar id\u00edlico para nuestro picnic en medio de las vacas de H\u00e9rens. Despu\u00e9s descendemos al Plan de l&#8217;Au, terminamos la ruta en Champex (1482 m) y tomamos un autob\u00fas para llegar al camping de La Fouly, pasando por encantadores pueblos tradicionales suizos.<br\/>Desnivel: 460 m, desnivel: 500 m<br\/> <br\/><strong>D\u00eda 3: De La Fouly a Val Ferret (lado italiano)<\/strong><br\/>Tras un breve traslado al fondo del valle (1802 m), subimos por los pastos de las monta\u00f1as suizas, para encontrarnos con los pastores y sus reba\u00f1os de ovejas, as\u00ed como con las famosas vacas grises con &#8220;orejas de oso&#8221;. Finalmente, llega al Gran Col Ferret (2490 m) en la frontera italo-suiza, con una vista impresionante de las caras sur del Mont Blanc macizo y el emblem\u00e1tico Mont Dolent. El descenso tiene lugar frente a los magn\u00edficos glaciares de Pr\u00e9 de Bar y Miage, que conducen al fondo del Val Ferret italiano en Arnuva (1769 m). Pasamos la noche en el camping de Planpincieux.<br\/>Desnivel: 500 m, desnivel: 600 m<br\/> <br\/><strong>D\u00eda 4: De Val Ferret a Courmayeur<\/strong><br\/>Emprendemos una deliciosa traves\u00eda de la Monta\u00f1a de Saxe, partiendo de la aldea de Lavachey (1650 m) y llegando al m\u00edtico refugio Walter Bonatti. A trav\u00e9s del encantador valle de Malatra, alcanzamos los puertos &#8220;Entre deux sauts&#8221; (2521 m) y &#8220;Col des Sapins&#8221; (2435 m) antes de seguir el camino del Val Sapin para llegar a la aldea de Villair Superiore. A continuaci\u00f3n, disfrutaremos de las delicias de Courmayeur y de un merecido helado, antes de dirigirnos al camping de Val Veny.<br\/>Desnivel: 650 m, desnivel: 700 m<br\/> <br\/><strong>D\u00eda 5: Val Veny aux Chapieux<\/strong><br\/>Partiendo de la aldea de La Visaille (1659 m), seguimos las aguas centelleantes del lago Combal, alcanzando poco a poco la frontera italo-francesa y el Col de la Seigne (2516 m), despidi\u00e9ndonos del lado italiano del Mont Blanc. Descendemos por los pintorescos pastos de monta\u00f1a de Beaufortin, con sus reba\u00f1os de cabras y sus vacas Tarines de ojos aterciopelados, para llegar finalmente a Les Chapieux, donde pasaremos la noche en el camping. <br\/>Desnivel: 500 m, desnivel: 600 m<br\/> <br\/><strong>D\u00eda 6 : De Les Chapieux a Les Contamines<\/strong><br\/>Hoy nos embarcaremos en una excursi\u00f3n al Col du Bonhomme (2433 m), atravesando impresionantes pastos de monta\u00f1a con posibilidad de encuentros sorprendentes.<br\/> <br\/><strong>D\u00eda 7: Chamonix<\/strong><br\/>Transporte a Chamonix y multiactividades<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-12 kt-pane16174_8d1c8f-92\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Un d\u00eda normal<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a, .wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a[data-kb-block=\"kb-adv-heading16174_d4f2ea-8a\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a[data-kb-block=\"kb-adv-heading16174_d4f2ea-8a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a[data-kb-block=\"kb-adv-heading16174_d4f2ea-8a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a, .wp-block-kadence-advancedheading.kt-adv-heading16174_d4f2ea-8a[data-kb-block=\"kb-adv-heading16174_d4f2ea-8a\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_d4f2ea-8a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_d4f2ea-8a\">7:00 h &#8211; Lev\u00e1ntate y desayuna en el campamento.<br\/>8:00 h &#8211; Preparaci\u00f3n del campamento e inicio del viaje en bicicleta<br\/>12:00 h &#8211; Parada para comer (bocadillo, galletas, fruta, etc.)<br\/>14:00 &#8211; Montaje del campamento para pasar la noche<br\/>15:00 &#8211; Explora los alrededores y programa actividades.<br\/>18:00 &#8211; Prepara la cena (comida liofilizada, sopa, etc.)<br\/>19:00 &#8211; Fogata y socializaci\u00f3n, programa educativo (astronom\u00eda, juego en equipo).<br\/>21:00 &#8211; Luces apagadas<br\/><br\/>Nota: \u00c9ste es s\u00f3lo un itinerario de muestra y las actividades pueden ajustarse seg\u00fan las necesidades y preferencias del grupo.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane16174_f179a4-68\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfQu\u00e9 equipo debo llevar?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37, .wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37[data-kb-block=\"kb-adv-heading16174_c3ac26-37\"]{padding-bottom:20px;font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37[data-kb-block=\"kb-adv-heading16174_c3ac26-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37[data-kb-block=\"kb-adv-heading16174_c3ac26-37\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37, .wp-block-kadence-advancedheading.kt-adv-heading16174_c3ac26-37[data-kb-block=\"kb-adv-heading16174_c3ac26-37\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_c3ac26-37 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_c3ac26-37\">Enumera el material:<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_7df7c9-ba{padding-top:10px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:flex-start;justify-content:center;}.kt-btns16174_7df7c9-ba .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_7df7c9-ba .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_7df7c9-ba .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_7df7c9-ba{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_7df7c9-ba\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_4a4d7b-2a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_4a4d7b-2a.kb-button{color:var(--global-palette3, #1A202C);font-size:16px;font-family:'Roboto Condensed';font-weight:600;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn16174_4a4d7b-2a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_4a4d7b-2a.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_4a4d7b-2a.kb-button{font-size:8px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_4a4d7b-2a kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/lista-de-materiales\/\"><span class=\"kt-btn-inner-text\">\u00a1LISTA AQU\u00cd!<\/span><\/a><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane16174_3fe3a0-4e\"><h2 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfTienes alguna otra pregunta?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h2><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49, .wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49[data-kb-block=\"kb-adv-heading16174_ad6d5d-49\"]{font-size:18px;line-height:23px;font-weight:500;font-style:normal;font-family:Nunito;}.wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49[data-kb-block=\"kb-adv-heading16174_ad6d5d-49\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49[data-kb-block=\"kb-adv-heading16174_ad6d5d-49\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49, .wp-block-kadence-advancedheading.kt-adv-heading16174_ad6d5d-49[data-kb-block=\"kb-adv-heading16174_ad6d5d-49\"]{font-size:14px;}}<\/style>\n<p class=\"kt-adv-heading16174_ad6d5d-49 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_ad6d5d-49\">Creemos en la interacci\u00f3n de persona a persona: escr\u00edbenos a trav\u00e9s de nuestros m\u00e9todos de contacto (https:\/\/youngexplorersclub.ch\/contact\/) y programa una llamada o una reuni\u00f3n con uno de nuestros empleados.<br\/>Estaremos encantados de responder a cualquier duda o pregunta que puedas tener.  <strong>O encuentra la lista de todas las preguntas frecuentes en Preguntas frecuentes.<\/strong><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id46932_1ee9a5-78 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id46932_1ee9a5-78 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id46932_1ee9a5-78 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:55px;padding-bottom:50px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id46932_1ee9a5-78 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46932_1ee9a5-78 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id46932_1ee9a5-78 > .kt-row-column-wrap{padding-top:20px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46932_1ee9a5-78 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{display:flex;}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col,.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column46932_b3c5e0-18{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46932_b3c5e0-18{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column46932_b3c5e0-18{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:flex-start;}.kt-row-column-wrap > .kadence-column46932_b3c5e0-18{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_b3c5e0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46932_b3c5e0-18\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee, .wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee[data-kb-block=\"kb-adv-heading46932_e9fd75-ee\"]{padding-top:0px;margin-top:0px;text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee[data-kb-block=\"kb-adv-heading46932_e9fd75-ee\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee[data-kb-block=\"kb-adv-heading46932_e9fd75-ee\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee, .wp-block-kadence-advancedheading.kt-adv-heading46932_e9fd75-ee[data-kb-block=\"kb-adv-heading46932_e9fd75-ee\"]{font-size:17px;}}<\/style>\n<h2 class=\"kt-adv-heading46932_e9fd75-ee wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading46932_e9fd75-ee\"><strong>Otros enlaces \u00fatiles<\/strong><\/h2>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-46932_679127-e5 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-46932_679127-e5 .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-46932_679127-e5 .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-46932_679127-e5\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97, .wp-block-kadence-advancedbtn.kb-btns46932_ccdd44-97, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns46932_ccdd44-97{margin-top:30px;}.wp-block-kadence-advancedbtn.kb-btns46932_ccdd44-97{gap:20px;flex-direction:column;align-items:center;justify-content:center;}.kt-btns46932_ccdd44-97 .kt-button{font-weight:normal;font-style:normal;}.kt-btns46932_ccdd44-97 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46932_ccdd44-97 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns46932_ccdd44-97\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_9409c4-d7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_9409c4-d7.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46932_9409c4-d7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_9409c4-d7.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_9409c4-d7.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_9409c4-d7 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/preguntas-frecuentes\/\"><span class=\"kt-btn-inner-text\">\u00bfM\u00c1S PREGUNTAS? Preguntas frecuentes.<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_dd32cd-1c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_dd32cd-1c.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46932_dd32cd-1c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_dd32cd-1c.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_dd32cd-1c.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_dd32cd-1c kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/nuestros-antiguos-campamentos\/\"><span class=\"kt-btn-inner-text\">Fotos y testimonios<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_8af91e-e6.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_8af91e-e6.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46932_8af91e-e6.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_8af91e-e6.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_8af91e-e6.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_8af91e-e6 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/nuestra-filosofia\/\"><span class=\"kt-btn-inner-text\">nuestra filosof\u00eda \u00daNICA.<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_29d401-4d.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_29d401-4d.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;margin-top:0px;}.wp-block-kadence-advancedbtn .kb-btn46932_29d401-4d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_29d401-4d.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_29d401-4d.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_29d401-4d kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"http:\/\/youngexplorersclub.ch\"><span class=\"kt-btn-inner-text\">Todos nuestros campamentos<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_de7820-a1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_de7820-a1.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46932_de7820-a1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_de7820-a1.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_de7820-a1.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_de7820-a1 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/nuestro-alojamiento\/\"><span class=\"kt-btn-inner-text\">Nuestros alojamientos<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46932_d2330b-fd.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46932_d2330b-fd.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:700;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:7px;padding-right:43px;padding-bottom:7px;padding-left:43px;}.wp-block-kadence-advancedbtn .kb-btn46932_d2330b-fd.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46932_d2330b-fd.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46932_d2330b-fd.kb-button{font-size:11px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn46932_d2330b-fd kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/contact\/\"><span class=\"kt-btn-inner-text\">contacta con nosotros<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46932_a758f2-77 > .kt-inside-inner-col{display:flex;}.kadence-column46932_a758f2-77 > .kt-inside-inner-col,.kadence-column46932_a758f2-77 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46932_a758f2-77 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46932_a758f2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column46932_a758f2-77 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column46932_a758f2-77{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column46932_a758f2-77 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46932_a758f2-77{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column46932_a758f2-77{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column46932_a758f2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46932_a758f2-77 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column46932_a758f2-77{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column46932_a758f2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46932_a758f2-77\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d, .wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d[data-kb-block=\"kb-adv-heading46932_1a346d-8d\"]{text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d[data-kb-block=\"kb-adv-heading46932_1a346d-8d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46932_1a346d-8d[data-kb-block=\"kb-adv-heading46932_1a346d-8d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading46932_1a346d-8d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading46932_1a346d-8d\"><strong>CONSIGUE AHORA LA GU\u00cdA 2026<\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71, .wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71[data-kb-block=\"kb-adv-heading46932_2c55ea-71\"]{text-align:center;font-weight:500;font-style:normal;font-family:Nunito;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71[data-kb-block=\"kb-adv-heading46932_2c55ea-71\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46932_2c55ea-71[data-kb-block=\"kb-adv-heading46932_2c55ea-71\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading46932_2c55ea-71 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading46932_2c55ea-71\">\u00a1No hacemos spam!<\/h4>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-46932_b7bed0-e6 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-46932_b7bed0-e6 .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:72px;border-top-style:solid;}@media all and (max-width: 767px){.wp-block-kadence-spacer.kt-block-spacer-46932_b7bed0-e6 .kt-divider{border-top-width:3px !important;width:72px!important;}}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-46932_b7bed0-e6\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kt-img-overlay46932_680d85-58{max-width:463px;width:100%;}.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-img-overlay46932_680d85-58{margin-left:unset;margin-right:unset;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:75%;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0.45 !important;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0.45 !important;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-color{background-color:var(--global-palette1, #3182CE);opacity:1;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-message{border-top:0px solid rgba(255,255,255,0.8);border-right:0px solid rgba(255,255,255,0.8);border-bottom:0px solid rgba(255,255,255,0.8);border-left:0px solid rgba(255,255,255,0.8);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay46932_680d85-58 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:24px;font-family:Roboto;font-weight:800;font-style:normal;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay46932_680d85-58 .kt-image-overlay-message .image-overlay-subtitle{color:var(--global-palette3, #1A202C);background:#ffffff;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-family:Nunito;font-weight:400;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay46932_680d85-58 .kt-image-overlay-wrap{max-width:637px;}}@media all and (max-width: 1024px){.kt-img-overlay46932_680d85-58 .kt-image-overlay-message{border-top:0px solid rgba(255,255,255,0.8);border-right:0px solid rgba(255,255,255,0.8);border-bottom:0px solid rgba(255,255,255,0.8);border-left:0px solid rgba(255,255,255,0.8);}}@media all and (max-width: 767px){.kt-img-overlay46932_680d85-58 .kt-image-overlay-wrap{max-width:637px;}.kt-img-overlay46932_680d85-58 .kt-image-overlay-message{border-top:0px solid rgba(255,255,255,0.8);border-right:0px solid rgba(255,255,255,0.8);border-bottom:0px solid rgba(255,255,255,0.8);border-left:0px solid rgba(255,255,255,0.8);}.wp-block-kadence-imageoverlay.kt-img-overlay46932_680d85-58 .kt-image-overlay-message .image-overlay-title{font-size:20px;line-height:15px;}.wp-block-kadence-imageoverlay.kt-img-overlay46932_680d85-58 .kt-image-overlay-message .image-overlay-subtitle{font-size:14px;line-height:13px;}}<\/style>\n<div class=\"kt-img-overlay46932_680d85-58 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img decoding=\"async\" src=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/2025-01-03-17_27_14-BROCHURE-EN-2025-WITHOUT-TEAM-Depliant-trois-volets-UE-Canva.png\" alt=\"Summer camp Switzerland, International summer camp\" width=\"637\" height=\"522\" class=\"kt-img-overlay wp-image-46438\" title=\"\" srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/2025-01-03-17_27_14-BROCHURE-EN-2025-WITHOUT-TEAM-Depliant-trois-volets-UE-Canva.png 637w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/2025-01-03-17_27_14-BROCHURE-EN-2025-WITHOUT-TEAM-Depliant-trois-volets-UE-Canva-150x123.png 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/2025-01-03-17_27_14-BROCHURE-EN-2025-WITHOUT-TEAM-Depliant-trois-volets-UE-Canva-500x410.png 500w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><a href=\"https:\/\/youngexplorersclub.ch\/es\/pagina-del-formulario-del-folleto\/\" class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><h3 class=\"image-overlay-title\" tabindex=\"0\">CONS\u00cdGUELO AQU\u00cd<\/h3><\/div><\/div><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id16174_71a919-38 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id16174_71a919-38 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id16174_71a919-38 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:24px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id16174_71a919-38 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id16174_71a919-38 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id16174_71a919-38 > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id16174_71a919-38 alignfull wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column16174_27ea9e-2c > .kt-inside-inner-col,.kadence-column16174_27ea9e-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_27ea9e-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_27ea9e-2c > .kt-inside-inner-col{flex-direction:column;}.kadence-column16174_27ea9e-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_27ea9e-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_27ea9e-2c{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_27ea9e-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column16174_27ea9e-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_27ea9e-2c\"><div class=\"kt-inside-inner-col\"><style>.kadence-column16174_a347c2-05 > .kt-inside-inner-col{display:flex;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col,.kadence-column16174_a347c2-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column16174_a347c2-05 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column16174_a347c2-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column16174_a347c2-05{position:relative;}@media all and (max-width: 1024px){.kadence-column16174_a347c2-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column16174_a347c2-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column16174_a347c2-05 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c, .wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c[data-kb-block=\"kb-adv-heading16174_44c387-3c\"]{padding-top:4px;text-align:center;font-size:26px;line-height:28px;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c[data-kb-block=\"kb-adv-heading16174_44c387-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_44c387-3c[data-kb-block=\"kb-adv-heading16174_44c387-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading16174_44c387-3c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_44c387-3c\"><strong><strong>la vuelta al campamento del mont blanc en Fotos<\/strong><\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e, .wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e[data-kb-block=\"kb-adv-heading16174_55ea0f-7e\"]{text-align:center;font-size:20px;line-height:23px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e[data-kb-block=\"kb-adv-heading16174_55ea0f-7e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e[data-kb-block=\"kb-adv-heading16174_55ea0f-7e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e, .wp-block-kadence-advancedheading.kt-adv-heading16174_55ea0f-7e[data-kb-block=\"kb-adv-heading16174_55ea0f-7e\"]{font-size:16px;}}<\/style>\n<p class=\"kt-adv-heading16174_55ea0f-7e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading16174_55ea0f-7e\">&#8221;Una imagen vale m\u00e1s que 1000 palabras&#8221;<\/p>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns16174_56b34e-94{padding-top:var(--global-kb-spacing-xs, 1rem);gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:column;align-items:center;justify-content:center;}.kt-btns16174_56b34e-94 .kt-button{font-weight:normal;font-style:normal;}.kt-btns16174_56b34e-94 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns16174_56b34e-94 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns16174_56b34e-94{align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns16174_56b34e-94\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn16174_dd3362-95.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn16174_dd3362-95.kb-button{color:var(--global-palette3, #1A202C);font-size:14px;font-family:'Roboto Condensed';font-weight:600;text-transform:uppercase;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:6px;padding-right:35px;padding-bottom:6px;padding-left:35px;}.wp-block-kadence-advancedbtn .kb-btn16174_dd3362-95.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn16174_dd3362-95.kb-button:focus{color:var(--global-palette3, #1A202C);}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn16174_dd3362-95.kb-button{font-size:11px;padding-top:7px;padding-right:30px;padding-bottom:7px;padding-left:30px;margin-top:0px;}}<\/style><a class=\"kb-button kt-button button kb-btn16174_dd3362-95 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/youngexplorersclub.ch\/es\/nuestros-antiguos-campamentos\/\"><span class=\"kt-btn-inner-text\">GALER\u00cdA: M\u00c1S IM\u00c1GENES Y V\u00cdDEOS aqu\u00ed<\/span><\/a><\/div>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-16174_4fb841-e8{overflow:hidden;}.kb-gallery-id-16174_4fb841-e8 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-16174_4fb841-e8 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-16174_4fb841-e8.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-16174_4fb841-e8.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}.kb-gallery-id-16174_4fb841-e8 .splide__arrow{font-size:var(--global-kb-font-size-md, 1.25rem);}<\/style><div class=\"kb-gallery-wrap-id-16174_4fb841-e8 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-carousel kb-gallery-id-16174_4fb841-e8 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-lightbox-caption=\"false\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-none kt-carousel-arrowstyle-blackonlight kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"5\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"3\" data-columns-xs=\"3\" data-columns-ss=\"3\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"2030\" data-slider-gap=\"3px\" data-slider-gap-tablet=\"3px\" data-slider-gap-mobile=\"3px\" data-show-pause-button=\"false\" data-slider-label=\"Galer\u00eda de fotos Carrusel\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-gallery-carousel splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1.jpg\" width=\"1620\" height=\"1080\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1.jpg 1620w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Bike-Travel-July-256-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" data-id=\"45355\" class=\"wp-image-45355 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy.jpg\" width=\"1440\" height=\"1080\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/Young-Explorers-Camps-2024-Adrenaline-June-1-341-Copy-1024x768.jpg 1024w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"45329\" class=\"wp-image-45329 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1.jpg\" width=\"1600\" height=\"1061\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1.jpg 1600w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1-150x99.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1-500x332.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1-768x509.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1-1024x679.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/1B45CA6F-DE66-4599-A9CD-66BF474005E7-1-1536x1019.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" data-id=\"45257\" class=\"wp-image-45257 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1.jpg\" width=\"1440\" height=\"1080\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/10\/68614BA6-C712-444E-88D1-BEB4C8BAE1A5-1-1024x768.jpg 1024w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"45268\" class=\"wp-image-45268 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9228-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64906\" class=\"wp-image-64906 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_9286-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64910\" class=\"wp-image-64910 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1.jpg\" width=\"1440\" height=\"1920\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1-375x500.jpg 375w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1-768x1024.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1-113x150.jpg 113w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8533-1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"64823\" class=\"wp-image-64823 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1.jpg\" width=\"1440\" height=\"1920\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1-375x500.jpg 375w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1-768x1024.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1-113x150.jpg 113w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8512-1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"64815\" class=\"wp-image-64815 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3.jpg\" width=\"1440\" height=\"1920\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3-375x500.jpg 375w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3-768x1024.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3-113x150.jpg 113w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_8286-3-1152x1536.jpg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"64773\" class=\"wp-image-64773 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2782-Copy-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64513\" class=\"wp-image-64513 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2428-Copy-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64482\" class=\"wp-image-64482 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_2472-Copy-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64485\" class=\"wp-image-64485 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3.jpg\" width=\"1920\" height=\"1440\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3-500x375.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3-1024x768.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3-150x113.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3-768x576.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/IMG_0694-2-3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64355\" class=\"wp-image-64355 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1.jpg\" width=\"1440\" height=\"1920\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1.jpg 1440w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1-375x500.jpg 375w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1-768x1024.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1-113x150.jpg 113w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSCF6801-1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-id=\"64283\" class=\"wp-image-64283 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC07003-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64232\" class=\"wp-image-64232 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06956-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64227\" class=\"wp-image-64227 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06892-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64221\" class=\"wp-image-64221 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06906-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64223\" class=\"wp-image-64223 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06919-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64224\" class=\"wp-image-64224 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06938-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64225\" class=\"wp-image-64225 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06888-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64220\" class=\"wp-image-64220 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06878-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64218\" class=\"wp-image-64218 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06875-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64217\" class=\"wp-image-64217 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06866-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64211\" class=\"wp-image-64211 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06868-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64212\" class=\"wp-image-64212 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2.jpg\" width=\"1280\" height=\"1920\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2.jpg 1280w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2-333x500.jpg 333w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2-683x1024.jpg 683w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2-100x150.jpg 100w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2-768x1152.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06869-2-1024x1536.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-id=\"64213\" class=\"wp-image-64213 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06871-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64214\" class=\"wp-image-64214 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2.jpg\" data-alt=\"Panoramic view of the Swiss Alps \u2013 setting for the best summer camp in Europe\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Panoramic view of the Swiss Alps \u2013 setting for the best summer camp in Europe\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06865-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64210\" class=\"wp-image-64210 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%201000%20667&#039;%3E%3C\/svg%3E\" data-splide-lazy=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2.jpg\" width=\"1920\" height=\"1280\" alt=\"Summer camp Switzerland, International summer camp\" data-full-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2.jpg\" data-light-image=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2.jpg\" data-splide-lazy-srcset=\"https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2.jpg 1920w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2-500x333.jpg 500w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2-1024x683.jpg 1024w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2-150x100.jpg 150w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2-768x512.jpg 768w, https:\/\/youngexplorersclub.ch\/wp-content\/uploads\/2025\/11\/DSC06822-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" data-id=\"64205\" class=\"wp-image-64205 skip-lazy\" title=\"\"><\/div><\/div><\/a><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id66485_3e9ca8-c8{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:var( --global-content-width, 1340px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:10px;padding-bottom:20px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id66485_3e9ca8-c8 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-none, 0rem );padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id66485_3e9ca8-c8 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column66485_64efe7-fd > .kt-inside-inner-col,.kadence-column66485_64efe7-fd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column66485_64efe7-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column66485_64efe7-fd > .kt-inside-inner-col{flex-direction:column;}.kadence-column66485_64efe7-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column66485_64efe7-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column66485_64efe7-fd{position:relative;}@media all and (max-width: 1024px){.kadence-column66485_64efe7-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column66485_64efe7-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column66485_64efe7-fd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88, .wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88[data-kb-block=\"kb-adv-heading66485_af323a-88\"]{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;text-align:center;font-weight:700;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88[data-kb-block=\"kb-adv-heading66485_af323a-88\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading66485_af323a-88[data-kb-block=\"kb-adv-heading66485_af323a-88\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading66485_af323a-88 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading66485_af323a-88\">ECHA UN VISTAZO A NUESTRO INSTAGRAM:<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2, .wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2[data-kb-block=\"kb-adv-heading66485_718e72-d2\"]{margin-right:0px;margin-left:0px;text-align:center;font-weight:500;font-style:normal;font-family:Nunito;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2[data-kb-block=\"kb-adv-heading66485_718e72-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2[data-kb-block=\"kb-adv-heading66485_718e72-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2, .wp-block-kadence-advancedheading.kt-adv-heading66485_718e72-d2[data-kb-block=\"kb-adv-heading66485_718e72-d2\"]{padding-right:0px;padding-left:0px;}}<\/style>\n<p class=\"kt-adv-heading66485_718e72-d2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading66485_718e72-d2\">Una colecci\u00f3n de peque\u00f1os momentos y actividades<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-66485_072a70-7d .kt-block-spacer{height:19px;}.wp-block-kadence-spacer.kt-block-spacer-66485_072a70-7d .kt-divider{border-top-width:5px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:75px;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-66485_072a70-7d\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<div style=\"margin-top:0;margin-bottom:0;height:var(--wp--preset--spacing--20)\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"wpsr-ig-feed-41530\" class=\"wpsr-ig-feed-wrapper wpsr-feed-wrap wpsr_content wpsr-ig-feed-template1 wpsr-ig-feed-template-41530  \"   data-column=\"3\"><div class=\"wpsr-container wpsr-insta-feed-41530\">\n    <div class=\"wpsr-ig-header wpsr-gap-narrow\">\n        <div class=\"wpsr-ig-header-inner\">\n            \n            <div class=\"wpsr-ig-header-info\">\n                                                                            <\/div>\n                        <div class=\"wpsr-ig-follow-btn\">\n                <a href=\"https:\/\/www.instagram.com\/clubyoungexplorers\" target=\"_blank\" rel=\"noopener\" aria-label=\"Follow on Instagram\">\n                    Follow on Instagram                <\/a>\n            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"wpsr-ig-feed-wrapper-inner\"><div class=\"wpsr-row wpsr-ig-all-feed wpsr_feeds wpsr-column-gap-narrow\"><\/div><div class=\"wpsr-ig-footer wpsr-row \"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>CAMPAMENTO DE VIAJES la visita al CAMPAMENTO del Mont Blanc un campamento de verano de mochileros para adolescentes Puntos clave del programa: El campamento de un vistazo: El campamento de verano de senderismo: Tour du Mont Blanc para adolescentes es una m\u00edtica e impresionante excursi\u00f3n de 7 d\u00edas alrededor del Mont Blanc macizo de los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[],"footnotes":""},"class_list":["post-18322","page","type-page","status-publish","hentry"],"wpml_language":null,"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"grivas","author_link":"https:\/\/youngexplorersclub.ch\/es\/author\/grivas\/"},"comment_info":"","_links":{"self":[{"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/pages\/18322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/comments?post=18322"}],"version-history":[{"count":10,"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/pages\/18322\/revisions"}],"predecessor-version":[{"id":71752,"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/pages\/18322\/revisions\/71752"}],"wp:attachment":[{"href":"https:\/\/youngexplorersclub.ch\/es\/wp-json\/wp\/v2\/media?parent=18322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}